{"id":95987,"date":"2022-02-04T11:07:38","date_gmt":"2022-02-04T10:07:38","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2022\/02\/04\/iss-in-calo-incidenza-rt-medio-e-trasmissibilita-covid\/"},"modified":"2022-02-04T11:07:38","modified_gmt":"2022-02-04T10:07:38","slug":"iss-in-calo-incidenza-rt-medio-e-trasmissibilita-covid","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2022\/02\/04\/iss-in-calo-incidenza-rt-medio-e-trasmissibilita-covid\/","title":{"rendered":"Iss, In calo incidenza, Rt medio e trasmissibilit\u00e0 Covid"},"content":{"rendered":"<div>ROMA (ITALPRESS) &#8211; Diminuzione dell&#8217;incidenza settimanale, dell&#8217;Rt medio ed anche della trasmissibilit\u00e0. Questi in sintesi i dati principali del monitoraggio della Cabina di Regia dell&#8217;Istituto Superiore di Sanit\u00e0 sul Covid-19. Si osserva, infatti, una diminuzione dell&#8217;incidenza settimanale a livello nazionale: 1362 ogni 100.000 abitanti (28\/01\/2022 -03\/02\/2021) vs 1823 ogni 100.000 abitanti (21\/01\/2022 -27\/01\/2021), dati flusso ministero Salute. Nel periodo 12 gennaio 2022 &#8211; 25 gennaio 2022, l&#8217;Rt medio calcolato sui casi sintomatici \u00e8 stato pari a 0,93 (range 0,9 &#8211; 0,98), in diminuzione rispetto alla settimana precedente e al di sotto della soglia epidemica. Lo stesso andamento si registra per l&#8217;indice di trasmissibilit\u00e0 basato sui casi con ricovero ospedaliero (Rt=0,89 (0,88-0,9) al 25\/01\/2022 vs Rt=0,96 (0,94-0,99) al 18\/01\/2022. Si sottolinea per\u00f2 che diverse Regioni\/PPAA hanno segnalato problemi nell&#8217;inserimento dei dati del flusso individuale ed in particolare nella segnalazione della presenza di sintomi in tutti i casi diagnosticati.<br \/>Il tasso di occupazione in terapia intensiva \u00e8 al 14,8% (rilevazione giornaliera Ministero della Salute al 3 febbraio) vs il 16,7% (rilevazione giornaliera Ministero della Salute al 27 gennaio). Il tasso di occupazione in aree mediche a livello nazionale \u00e8 al 29,5% (rilevazione giornaliera Ministero della Salute al 3 febbraio) vs il 30,4% (rilevazione giornaliera Ministero della Salute al 27 gennaio).<br \/>Tre Regioni\/PPAA sono classificate a rischio Alto, secondo il DM del 30 aprile 2020, a causa dell&#8217;impossibilit\u00e0 di valutazione per incompletezza dei dati inviati; 3 Regioni\/PPAA risultano classificate a rischio Moderato. Tra queste, una Regione\/PA \u00e8 ad alta probabilit\u00e0 di progressione a rischio Alto secondo il DM del 30 aprile 2020. Le restanti 15 Regioni\/PPAA sono classificate a rischio basso. 10 Regioni\/PPAA riportano almeno una singola allerta di resilienza. Una Regione\/PA riporta molteplici allerte di resilienza.<br \/>Diminuisce il numero di nuovi casi non associati a catene di trasmissione (553.860 vs 652.401 della settimana precedente). La percentuale dei casi rilevati attraverso l&#8217;attivit\u00e0 di tracciamento dei contatti \u00e8 in leggera diminuzione (17% vs 18% la scorsa settimana). E&#8217; stabile invece la percentuale dei casi rilevati attraverso la comparsa dei sintomi (38% vs 38%) ed anche la percentuale di casi diagnosticati attraverso attivit\u00e0 di screening (45% vs 45%).<br \/>(ITALPRESS).<\/div>\n<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p><div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; Diminuzione dell&#8217;incidenza settimanale, dell&#8217;Rt medio ed anche della trasmissibilit\u00e0. Questi in sintesi i dati principali del monitoraggio della Cabina di Regia dell&#8217;Istituto Superiore di Sanit\u00e0 sul Covid-19. Si osserva, infatti, una diminuzione dell&#8217;incidenza settimanale a livello nazionale: 1362 ogni 100.000 abitanti (28\/01\/2022 -03\/02\/2021) vs 1823 ogni 100.000 abitanti (21\/01\/2022 -27\/01\/2021), dati flusso [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":95988,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[446],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2022\/02\/20220204_0241.jpg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/95987"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=95987"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/95987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/95988"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=95987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=95987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=95987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}