{"id":7566,"date":"2017-09-11T10:27:27","date_gmt":"2017-09-11T08:27:27","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=7566"},"modified":"2017-09-11T10:27:27","modified_gmt":"2017-09-11T08:27:27","slug":"tennis-giorgio-tabacco-vice-campione-ditalia-under-14","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2017\/09\/11\/tennis-giorgio-tabacco-vice-campione-ditalia-under-14\/","title":{"rendered":"Tennis: Giorgio Tabacco vice campione d&#039;Italia Under 14"},"content":{"rendered":"<p>Solo un ottimo Luca Nardi (2.5 e numero 1 del seeding) ha fermato la corsa Giorgio Tabacco verso il titolo di campione italiano Under 14 di tennis. Nella finale disputata a Roma (sui campi in terra rossa del Ct Eur) Nardi si \u00e8 imposto con il punteggio di 6-1 6-4, ma il match \u00e8 stato molto intenso e interessante e nella seconda partita Tabacco era avanti 4 a 1 e ha avuto molte opportunit\u00e0 per conquistare il quinto game.<br \/>\n\u00c8 stata una settimana importante per il portacolori del Ctv Messina che sino al match odierno aveva concesso solo pochi giochi agli avversari. Dopo aver superato, in ordine,\u00a0Filippo Scalseggi\u00a0(6-0 6 1),\u00a0Flavio Mario Pasquariello (6-2 6-3) e il palermitano Gabriele Piraino (6-0 6-1), in semifinale Tabacco ha sconfitto, al termine di un match davvero ben giocato, Alessio Tramontin (protagonista a giugno allo \u201cStagno d\u2019Alcontres\u201d, quando sprec\u00f2 due match point con Pinnington Jones che poi si aggiudic\u00f2 il torneo) in due set per 6-4 6-2.<br \/>\nIn finale la sfida con il pesarese Luca Nardi (campione anche in doppio in coppia con Alessio Tramontin). Dopo un primo set vinto per 6-1 da Nardi, nella seconda partita Tabacco \u00e8 salito in cattedra conducendo sino al 4 a 1, poi sul 4 a 2 ha avuto ben 5 palle per conquistare il quinto game, sul 4 a 3 e servizio Nardi tre break point e, sul 4 pari e servizio Tabacco, il numero 1 del seeding \u00e8 riuscito a strappare il servizio al messinese da 40-15, chiudendo poi nel turno di battuta successivo.<br \/>\nTabacco (accompagnato a Roma da direttore tecnico del Ctv Gino Visali e dal maestro Antonio Fam\u00e0) ha evidenziato notevoli progressi che lasciano ben sperare per il futuro.<br \/>\nIn campo femminile (si \u00e8 giocato sul rosso del Due Ponti) \u00e8 Lisa Pigato la nuova campionessa Under 14. La giovane tennista lombarda ha piegato la resistenza di Matilde Paoletti per 6-1 6-3. La Pigato si \u00e8 poi ripetuta in doppio proprio in coppia con la Paoletti: le due ragazze si sono imposte in finale per 7-6 (5) 6-4 su Asia Serafini ed Eleonora Alvisi.<br \/>\n <div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>Solo un ottimo Luca Nardi (2.5 e numero 1 del seeding) ha fermato la corsa Giorgio Tabacco verso il titolo di campione italiano Under 14 di tennis. Nella finale disputata a Roma (sui campi in terra rossa del Ct Eur) Nardi si \u00e8 imposto con il punteggio di 6-1 6-4, ma il match \u00e8 stato [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7567,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[8,9],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2017\/09\/giorgio-tabacco-tennista-2.jpg","author_info":{"display_name":"Redazione","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redazione\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/7566"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=7566"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/7566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/7567"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=7566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=7566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=7566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}