{"id":6153,"date":"2017-08-09T09:00:14","date_gmt":"2017-08-09T07:00:14","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=6153"},"modified":"2017-08-09T09:00:14","modified_gmt":"2017-08-09T07:00:14","slug":"van-gogh-multimedia-experience-eventi-speciali-per-la-notte-di-san-lorenzo","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2017\/08\/09\/van-gogh-multimedia-experience-eventi-speciali-per-la-notte-di-san-lorenzo\/","title":{"rendered":"&quot;Van Gogh multimedia Experience&quot;, eventi speciali per la notte di San Lorenzo"},"content":{"rendered":"<p><strong>&#8220;Ad Agosto Van Gogh mio ti&#8230;.conosco&#8221;,<\/strong> \u00e8 questo il doppio appuntamento della &#8220;Van Gogh multimedia Experience&#8221; che per la notte di San Lorenzo di gioved\u00ec dieci agosto, in omaggio alla notte delle stelle e del famoso quadro del pittore olandese, rimarr\u00e0 aperta fino mezzanotte a disposizione di quanti vorranno raggiungere, Palazzo Corvaja, nelle cui sale antiche, \u00e8 stata allestita l&#8217;esposizione multimediale gi\u00e0 visitata da migliaia di spettatori. Venerd\u00ec 11 agosto, dalle 10 alle 14, Van Gogh aprir\u00e0, idealmente, le porte di casa&#8230;&#8230; per quanti vorranno immergersi nella vita di questo conosciutissimo artista<br \/>\n<strong><u>Giovedi 10 agosto<\/u><\/strong> in occasione della notte di San Lorenzo, verr\u00e0 sorteggiato un biglietto, tra quelli acquistati nel pomeriggio. Il vincitore porter\u00e0 a casa un cuscino con la bellissima \u201cNotte Stellata\u201d, sorteggio tra i biglietti acquistati dalle 17,00 alle 22,30<br \/>\n<strong><u>Venerd\u00ec 11 agosto\u00a0<\/u><\/strong>Van Gogh aprir\u00e0 le porte di casa\u2026..vostra! in occasione del Van Gogh\u2019sday, tutti i visitatori che ci verranno a trovare alla mostra presso il Palazzo Corvaja a Taormina\u00a0 dalle 10,00 alle 14,00 riceveranno in omaggio uno dei nostri portachiavi dedicati all\u2019artista<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>&#8220;Ad Agosto Van Gogh mio ti&#8230;.conosco&#8221;, \u00e8 questo il doppio appuntamento della &#8220;Van Gogh multimedia Experience&#8221; che per la notte di San Lorenzo di gioved\u00ec dieci agosto, in omaggio alla notte delle stelle e del famoso quadro del pittore olandese, rimarr\u00e0 aperta fino mezzanotte a disposizione di quanti vorranno raggiungere, Palazzo Corvaja, nelle cui sale [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5437,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[3],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2017\/07\/van-gogh-a-taormina-2.jpg","author_info":{"display_name":"Redazione","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redazione\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/6153"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=6153"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/6153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/5437"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=6153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=6153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=6153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}