{"id":58643,"date":"2021-04-07T13:07:31","date_gmt":"2021-04-07T11:07:31","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2021\/04\/07\/vaccini-un-sondaggio-cresce-la-fiducia-in-johnson-johnson\/"},"modified":"2021-04-07T13:07:31","modified_gmt":"2021-04-07T11:07:31","slug":"vaccini-un-sondaggio-cresce-la-fiducia-in-johnson-johnson","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2021\/04\/07\/vaccini-un-sondaggio-cresce-la-fiducia-in-johnson-johnson\/","title":{"rendered":"Vaccini, un sondaggio: cresce la fiducia in Johnson &amp; Johnson"},"content":{"rendered":"<div>ROMA (ITALPRESS) &#8211; Per una vaccinazione pi\u00f9 capillare ed efficiente, 3 italiani su 4 sarebbero favorevoli a rendere il vaccino obbligatorio, non solo per gli operatori sanitari, ma anche per tutti i cittadini (il 46,4% per tutti, il 30,5% solo per i sanitari). E&#8217; quanto risulta da un sondaggio di Euromedia Research. <br \/>Dopo le sospensioni, la fiducia nel vaccino Astrazeneca (ora Vaxzevria) continua ad avere un andamento altalenante, mentre crescono le preferenze per il siero Johnson&amp;Johnson, anche se ancora non ufficialmente in fase di somministrazione. In testa alle preferenze del campione resta tuttavia Pfizer <br \/>Il piano di vaccinazione non sempre \u00e8 stato rispettato e, nel caso della copertura degli over 80, sono state percepite importanti differenze a livello regionale da quasi la met\u00e0 del campione. Percezioni molto pi\u00f9 forti soprattutto nelle aree del Nord Ovest del Paese e al Sud, mentre le regioni del Nord Est sono quelle che, in prevalenza, credono non ci siano difficolt\u00e0 nell&#8217;andamento delle vaccinazioni.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<p>Dati Euromedia Research &#8211; Realizzato il 31\/03\/2021 con metodologia mista CATI\/CAWI su un campione di 1.000 casi rappresentativi della popolazione italiana maggiorenne<br \/>(ITALPRESS).<\/div>\n<div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; Per una vaccinazione pi\u00f9 capillare ed efficiente, 3 italiani su 4 sarebbero favorevoli a rendere il vaccino obbligatorio, non solo per gli operatori sanitari, ma anche per tutti i cittadini (il 46,4% per tutti, il 30,5% solo per i sanitari). E&#8217; quanto risulta da un sondaggio di Euromedia Research. Dopo le sospensioni, [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":58644,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[446],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2021\/04\/20210407_0324.jpg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/58643"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=58643"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/58643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/58644"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=58643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=58643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=58643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}