{"id":5428,"date":"2017-07-25T22:28:36","date_gmt":"2017-07-25T20:28:36","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=5428"},"modified":"2017-07-25T22:28:36","modified_gmt":"2017-07-25T20:28:36","slug":"tragico-incidente-un-morto-e-un-ferito","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2017\/07\/25\/tragico-incidente-un-morto-e-un-ferito\/","title":{"rendered":"Incidente a Capo Al\u00ec, muore scooterista"},"content":{"rendered":"<p>Tragico incidente stradale a Capo Al\u00ec .<br \/>\nUn uomo di 48 anni, Letterio Manganaro, ha perso la vita dopo essere stato urtato da un&#8217;auto.<br \/>\nLa dinamica dell&#8217;incidente non \u00e8 ancora chiara. Sembra che la vittima, in sella ad uno scooter, sia stata toccata da una macchina che lo avrebbe stretto per evitare lo scontro frontale con un&#8217;altra vettura.<br \/>\nL&#8217;incidente si \u00e8 verificato ieri sera intorno alle 21.30 in contrada Siberia, nei tornanti di Capo Ali.<br \/>\nPer lo sfortunato scooterista non c&#8217;\u00e8 stato nulla da fare, vani i tentativi di rianimarlo. Rilievi di legge affidati ai carabinieri diretti da Ivan Barsottini.<br \/>\nLa circolazione stradale \u00e8 stata paralizzata per quasi due ore.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>Tragico incidente stradale a Capo Al\u00ec . Un uomo di 48 anni, Letterio Manganaro, ha perso la vita dopo essere stato urtato da un&#8217;auto. La dinamica dell&#8217;incidente non \u00e8 ancora chiara. Sembra che la vittima, in sella ad uno scooter, sia stata toccata da una macchina che lo avrebbe stretto per evitare lo scontro frontale [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1992,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[13,15],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2017\/06\/ambulanza-118-1-2.jpg","author_info":{"display_name":"Redazione","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redazione\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/5428"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=5428"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/5428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/1992"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=5428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=5428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=5428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}