{"id":47342,"date":"2020-09-20T18:30:47","date_gmt":"2020-09-20T16:30:47","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/?p=47342"},"modified":"2020-09-20T18:30:47","modified_gmt":"2020-09-20T16:30:47","slug":"basket-fabrizio-musico-nuovo-team-manager-del-castanea-basket-2010","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2020\/09\/20\/basket-fabrizio-musico-nuovo-team-manager-del-castanea-basket-2010\/","title":{"rendered":"BASKET &#8211; Fabrizio Music\u00f2 nuovo team manager del Castanea Basket 2010"},"content":{"rendered":"<p style=\"text-align: justify\">Il Castanea Basket 2010 presenta un\u2019altra pedina che si inserisce nel folto organigramma societario in vista della stagione sportiva 2020\/21. Fabrizio Music\u00f2 \u00e8 infatti il nuovo team manager della societ\u00e0 del presidente Alessandro Sacc\u00e0 attesa dalla nuova emozionante avventura in serie C Silver.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<p style=\"text-align: justify\">Il giovane dirigente peloritano ha gi\u00e0 esordito lo scorso anno all\u2019interno della famiglia gialloviola occupandosi di problematiche inerenti la prima squadra e curando in particolar modo i rapporti logistici con gli atleti stranieri. Il campionato di serie D, interrotto improvvisamente a seguito delle note problematiche sanitarie, \u00e8 poi culminato con l\u2019ammissione in massima serie regionale regalando allo stesso dirigente messinesi un epilogo indimenticabile.<div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n<p style=\"text-align: justify\">Adesso il suo impegno a favore del club diventa ufficiale e si consolida ad un livello tecnico certamente superiore, dovr\u00e0 infatti curare tutti i rapporti tra la dirigenza, lo staff tecnico e i giocatori mettendo in comunicazione tutti i principali settori della societ\u00e0, ascoltando le varie esigenze e provando a facilitare ed agevolare la permanenza dei nuovi ragazzi in riva allo Stretto.<\/p>\n<p style=\"text-align: justify\">Questo il commento del team manager Fabrizio Music\u00f2: \u201c<em>Mi sono avvicinato lo scorso anno alla famiglia del Castanea Basket, societ\u00e0 alla quale mi lega un\u2019amicizia profonda con l\u2019attuale propriet\u00e0 che conosco ormai da diversi anni. I dirigenti conoscendo la mia passione per la pallacanestro e lo sport in genere mi hanno proposto questo incarico che non potevo certamente rifiutare. Il mio obiettivo \u00e8 sempre quello di fornire un supporto concreto alla societ\u00e0, lo sport \u00e8 una mia grande passione e ogni giorno sto conoscendo aspetti sempre nuovi di questo magnifico mondo che riesce a regalare settimanalmente <\/em><em>grandi emozioni a chi lo guarda. Non sar\u00e0 un anno facile, il Covid infatti sta condizionando il nostro lavoro e complica i programmi di ogni societ\u00e0 ma sono certo che, unendo le forze e rispettando i protocolli sanitari, riusciremo a portare a termine la stagione. Non vedo l\u2019ora di cominciare a lavorare al fianco della squadra e cercher\u00f2 di risolvere ogni pi\u00f9 disparata esigenza che durante una stagione lunga come la nostra pu\u00f2 sempre presentarsi<\/em>\u201d.<\/p>\n<p style=\"text-align: justify\">Il Castenea Basket 2010 formula il proprio benvenuto al team manager Fabrizio Music\u00f2 ed augura un in bocca al lupo per il lavoro che lo attende.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Castanea Basket 2010 presenta un\u2019altra pedina che si inserisce nel folto organigramma societario in vista della stagione sportiva 2020\/21. Fabrizio Music\u00f2 \u00e8 infatti il nuovo team manager della societ\u00e0 del presidente Alessandro Sacc\u00e0 attesa dalla nuova emozionante avventura in serie C Silver. Il giovane dirigente peloritano ha gi\u00e0 esordito lo scorso anno all\u2019interno della [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":47343,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[8,9],"tags":[202,343],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2020\/09\/Fabrizio-Musico.jpg","author_info":{"display_name":"Giuseppe Luppino","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/g-luppino\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/47342"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=47342"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/47342\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/47343"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=47342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=47342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=47342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}