{"id":4717,"date":"2017-07-13T14:42:50","date_gmt":"2017-07-13T12:42:50","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=4717"},"modified":"2017-07-13T14:42:50","modified_gmt":"2017-07-13T12:42:50","slug":"van-gogh-multimedia-experience-il-20-luglio-si-alza-il-sipario-a-palazzo-corvaja","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2017\/07\/13\/van-gogh-multimedia-experience-il-20-luglio-si-alza-il-sipario-a-palazzo-corvaja\/","title":{"rendered":"\u201cVan Gogh Multimedia Experience\u201d: il 20 luglio si alza il sipario a Palazzo Corvaja"},"content":{"rendered":"<p>&#8220;Finalmente al via un&#8217;esperienza unica&#8221;. Lo ha detto Tot\u00f2 La Cagnina, delegato della &#8220;Bi Cubo srl&#8221; che si appresta ad avviare un appuntamento multimediale di grande spessore. A partire dal 20 luglio, nelle splendide sale di Palazzo Corvaja, si svolger\u00e0 il \u201cVan Gogh Multimedia Experience\u201d. Un\u2019esposizione multisensoriale questa all\u2019interno della quale lo spettatore si immetter\u00e0, per un&#8217;ora circa, nel mondo del celebre pittore olandese, vivendo un\u2019esperienza di grandi emozioni attraverso un ricco percorso.<br \/>\nI dettagli della performance sono stati resi noti nel corso di una conferenza alla quale hanno preso parte gli amministratori della Citt\u00e0 del Centauro. &#8220;Adesso prender\u00e0 il via &#8211; ha annunciato il vice sindaco ed assessore alla Cultura, Andrea Raneri &#8211; un appuntamento importante. Quanto finora accaduto ci da lo spunto per avviare un regolamento sulle concessioni degli spazi di pertinenza comunale che \u00e8 gi\u00e0 in commissione consiliare&#8221;.<br \/>\nMa l&#8217;appuntamento multimediale viene considerato anche un buon viatico per l&#8217;industria turistica. &#8220;Siamo certi che l&#8217;iniziativa che si sta avviando &#8211; ha affermato l&#8217;assessore al Turismo, Salvo Cilona &#8211; pu\u00f2 essere considerato un quid in pi\u00f9 per i gentili ospiti che trascorrono le vacanze nella nostra citt\u00e0&#8221;. L\u2019inaugurazione della mostra si svolger\u00e0, appunto, il 20 luglio, con inizio alle 19 e l&#8217;ingresso all&#8217;esposizione sar\u00e0 possibile fino alle 24, sempre a Palazzo Corvaja.<br \/>\n\u00c8 annunciata la presenza dell&#8217;attore, Bruno Torrisi, assieme al soprano, Marianna Cappellani. Si stanno preparando momenti artistici di grandissimo livello per presentare un&#8217;iniziativa realizzata in onore del pittore olandese ed annunciare l\u2019apertura della mostra, evento culturale che la citt\u00e0 di Taormina si appresta ad ospitare per poco pi\u00f9 di due mesi.<br \/>\nLa mostra si sviluppa in pi\u00f9 sale, con spazi adibiti alla visione delle immagini suggestive delle opere di Van Gogh. All\u2019inizio della mostra saranno presenti pannelli esplicativi dedicati a far conoscere vita e opere dell&#8217;artista. Il percorso \u00e8 inserito in appositi totem a tema con video contenenti le opere raccolte attraverso foto in alta definizione che descriveranno vita ed opere realizzate negli ultimi dieci anni della sua breve esistenza che hanno, per\u00f2, influenzato l\u2019arte moderna. Lo scopo della mostra \u00e8, essenzialmente, divulgativo e culturale.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>&#8220;Finalmente al via un&#8217;esperienza unica&#8221;. Lo ha detto Tot\u00f2 La Cagnina, delegato della &#8220;Bi Cubo srl&#8221; che si appresta ad avviare un appuntamento multimediale di grande spessore. A partire dal 20 luglio, nelle splendide sale di Palazzo Corvaja, si svolger\u00e0 il \u201cVan Gogh Multimedia Experience\u201d. Un\u2019esposizione multisensoriale questa all\u2019interno della quale lo spettatore si immetter\u00e0, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1184,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[3],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2017\/06\/corvaja-2.jpg","author_info":{"display_name":"Redazione","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redazione\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/4717"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=4717"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/4717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/1184"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=4717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=4717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=4717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}