{"id":46661,"date":"2020-08-20T23:22:06","date_gmt":"2020-08-20T21:22:06","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/?p=46661"},"modified":"2020-08-20T23:22:06","modified_gmt":"2020-08-20T21:22:06","slug":"giallo-di-caronia-vdf-siamo-addolorati-vicini-al-dolore-di-daniele","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2020\/08\/20\/giallo-di-caronia-vdf-siamo-addolorati-vicini-al-dolore-di-daniele\/","title":{"rendered":"Giallo di Caronia. VdF: &quot;Siamo addolorati, vicini al dolore di Daniele&quot;"},"content":{"rendered":"<p>Una tragedia immane che lascia un segno anche agli stessi soccorritori. Cos\u00ec i vigili del fuoco esprimono il loro dolore: &#8220;Siamo profondamente addolorati per la tragedia di Caronia e siamo vicini al dolore di pap\u00e0 Daniele. Tutto il nostro personale, tutti i vigili del fuoco che hanno partecipato e si sono impegnati senza sosta nelle ricerche, si stringono intorno a lui.<br \/>\nIn queste giornate terribili, dopo aver trovato qualche giorno fa il corpo senza vita di mamma Viviana, animati da un forte sentimento di speranza, abbiamo fatto tutto il possibile, insieme ad altri Enti ed Istituzioni coinvolte nelle ricerche, per trovare anche Gioele.<br \/>\nGrazie all&#8217;accorato appello del padre ed alla cassa di risonanza che proprio i mezzi d&#8217;informazione hanno fatto a questa tragica vicenda, c&#8217;\u00e8 stato un nuovo impulso alle ricerche fornito dai residenti del luogo che volontariamente si sono uniti agli uomini e alle donne delle istituzioni ed ai volontari organizzati, gi\u00e0 impegnati gi\u00e0 sul campo, apportando un indiscusso valore aggiunto all&#8217;attivit\u00e0, grazie anche alla specifica conoscenza del territorio&#8221;.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>Una tragedia immane che lascia un segno anche agli stessi soccorritori. Cos\u00ec i vigili del fuoco esprimono il loro dolore: &#8220;Siamo profondamente addolorati per la tragedia di Caronia e siamo vicini al dolore di pap\u00e0 Daniele. Tutto il nostro personale, tutti i vigili del fuoco che hanno partecipato e si sono impegnati senza sosta nelle [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":46397,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[6],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2020\/08\/2ED99558-E585-42B9-821D-8EA5545C906B.jpeg","author_info":{"display_name":"redme","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redme\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/46661"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=46661"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/46661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/46397"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=46661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=46661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=46661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}