{"id":43957,"date":"2020-05-25T21:38:03","date_gmt":"2020-05-25T19:38:03","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/?p=43957"},"modified":"2020-05-25T21:38:03","modified_gmt":"2020-05-25T19:38:03","slug":"modificano-la-spiaggia-tre-denunciati-a-galati-marina","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2020\/05\/25\/modificano-la-spiaggia-tre-denunciati-a-galati-marina\/","title":{"rendered":"Modificano la spiaggia, tre denunciati a Galati Marina"},"content":{"rendered":"<p>La squadra Spiaggia e Torrenti della Polizia municipale, al comando del commissario Giovanni Giardina, \u00e8 intervenuta presso l&#8217;arenile di Galati dove un uomo, su commissione di due proprietari di immobili posti a confine con la spiaggia, ha modificato, con l&#8217;ausilio di un Carterpillar, l&#8217;arenile a favore delle abitazioni.<br \/>\nL&#8217;intervento &#8220;fai da te&#8221; \u00e8 avvenuto ad una settimana dall&#8217;ultima sistemazione dei massi frangiflutti ad opera del Comune, dopo che un altro proprietario si era fatto lecito spostare i massi della barriera a ridosso ed ha maggior protezione della propria abitazione.<br \/>\nTre persone sono state deferite all&#8217;Autorit\u00e0 giudiziaria per la violazione agli artt. 54 e 1161 Codice della Navigazione mentre il mezzo d&#8217;opera \u00e8 stato sottoposto a sequetro giudiziario.<br \/>\nL&#8217;intervento ha fatto emergere ulteriori abusi; \u00e8 stata accertata l&#8217;occupazione di 600 mq di area demaniale in assenza della prescritta concessione di demaniale.<br \/>\n<img loading=\"lazy\" class=\"alignnone size-medium wp-image-43959\" src=\"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2020\/05\/IMG-20200525-WA0025-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><br \/>\nPer tale illecito sono state deferite tre persona all&#8217;autorit\u00e0 giudiziaria per la violazione agli artt. 633, 635 e 639 bis C.P. e le aree, che erano state delimitate con l&#8217;edificazione di muri in cemento armato di altezza fino a 2,50mt, sottoposte a sequetro.<br \/>\n<img loading=\"lazy\" class=\"alignnone size-medium wp-image-43960\" src=\"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2020\/05\/IMG-20200525-WA0024-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><br \/>\nSempre nell&#8217;ambito dello stesso intervento si \u00e8 accertato un abuso edilizio che ha determinato l&#8217;aumento di volume abitativo in assenza di Permesso di costruire, anche questo verbalizzato ai sensi degli art. 44, 93, 94 e 95 D.P.R 380\/01<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>La squadra Spiaggia e Torrenti della Polizia municipale, al comando del commissario Giovanni Giardina, \u00e8 intervenuta presso l&#8217;arenile di Galati dove un uomo, su commissione di due proprietari di immobili posti a confine con la spiaggia, ha modificato, con l&#8217;ausilio di un Carterpillar, l&#8217;arenile a favore delle abitazioni. L&#8217;intervento &#8220;fai da te&#8221; \u00e8 avvenuto ad [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":43958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[6],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2020\/05\/IMG-20200525-WA0026.jpg","author_info":{"display_name":"redme","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redme\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/43957"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=43957"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/43957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/43958"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=43957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=43957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=43957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}