{"id":41851,"date":"2020-03-30T21:41:34","date_gmt":"2020-03-30T19:41:34","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/?p=41851"},"modified":"2020-03-30T21:41:34","modified_gmt":"2020-03-30T19:41:34","slug":"caffe-barbera-attiva-rete-di-solidarieta-e-adotta-500-famiglie-messinesi","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2020\/03\/30\/caffe-barbera-attiva-rete-di-solidarieta-e-adotta-500-famiglie-messinesi\/","title":{"rendered":"Caff\u00e8 Barbera, attiva rete di solidariet\u00e0 e &quot;adotta&quot; 500 famiglie messinesi"},"content":{"rendered":"<p style=\"text-align: justify;\">La storica azienda messinese &#8220;Caff\u00e8 Barbera&#8221;, vista l&#8217;emergenza sociale scatenata dal Coronavirus, ha deciso di attivare una rete di solidariet\u00e0 &#8220;adottando&#8221; \u00a0500 famiglie messinesi.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<p style=\"text-align: justify;\">&#8220;<em>La crisi colpisce tutti, ma a pagarne le conseguenze, come sempre sono le fasce sociali pi\u00f9 deboli. Per questo motivo, la Caff\u00e8 Barbera ha deciso di acquistare, attraverso il gruppo Sigma della grande distribuzione, 11 pedane di prima necessit\u00e0, a cui sar\u00e0 aggiunto il Caff\u00e8 Barbera, finalizzati ad aiutare le famiglie gi\u00e0 in situazioni di disagio che l&#8217;emergenza sanitaria ha messo in ginocchio<\/em>&#8220;.<div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n<p style=\"text-align: justify;\">Lo annuncia la famiglia Barbera che ha deciso di aderire alle iniziative solidali in soccorso delle famiglie in difficolt\u00e0. I prodotti acquistati saranno recapitati ai nuclei familiari messinesi con problemi di sussistenza, attraverso la Messina Social City.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La storica azienda messinese &#8220;Caff\u00e8 Barbera&#8221;, vista l&#8217;emergenza sociale scatenata dal Coronavirus, ha deciso di attivare una rete di solidariet\u00e0 &#8220;adottando&#8221; \u00a0500 famiglie messinesi. &#8220;La crisi colpisce tutti, ma a pagarne le conseguenze, come sempre sono le fasce sociali pi\u00f9 deboli. Per questo motivo, la Caff\u00e8 Barbera ha deciso di acquistare, attraverso il gruppo Sigma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[6],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2019\/05\/grocery-15.jpg","author_info":{"display_name":"Redazione","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redazione\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/41851"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=41851"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/41851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/32624"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=41851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=41851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=41851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}