{"id":39451,"date":"2020-01-01T23:45:24","date_gmt":"2020-01-01T22:45:24","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/?p=39451"},"modified":"2020-01-01T23:45:24","modified_gmt":"2020-01-01T22:45:24","slug":"scoppia-incendio-in-una-palazzina-5-intossicati-2-gravi","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2020\/01\/01\/scoppia-incendio-in-una-palazzina-5-intossicati-2-gravi\/","title":{"rendered":"Scoppia incendio in una palazzina: 5 intossicati, 2 gravi"},"content":{"rendered":"<p>Panico in un condominio di via Consolarea Pompea, a Paradiso, a causa di un incendio sviluppatosi al pianoterra dello stabile.<br \/>\n<img loading=\"lazy\" class=\"size-medium wp-image-39448 alignleft\" src=\"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2020\/01\/CB3D7F6C-7AA5-496B-B722-4EDDF101B74A-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" \/><br \/>\nIl fumo ha invaso gli appartamenti dei piani soprastanti e quasi tutti gli occupanti li hanno dovuti abbandonare frettolosamente.<br \/>\nAlcuni anziani sono rimasti per\u00f2 intrappolati in casa e sono dovuti intervenire i vigili del fuoco giunti sul posto dopo che \u00e8 scattato l&#8217;allarme, per trarli in salvo con le autoscale. Si sono vissuti momenti di panico, intorno alle 8 di oggi, lungo la litoranea dove \u00e8 divampato l&#8217;incendio in un&#8217;abitazione.<br \/>\nLe fiamme si sarebbero scatenate accidentalmente: comunque stanno indagando i poliziotti delle Volanti.<br \/>\nDue coniugi anziani sono stati condotti all&#8217;ospedale Papardo in codice rosso e le condizioni vengono definite gravi dai sanitari. Gli altri intossicati sono stati condotti in via precauzionale in ospedale per essere sottoposti a controlli.<br \/>\n<img loading=\"lazy\" class=\"size-medium wp-image-39450 alignright\" src=\"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2020\/01\/D3E3E797-707D-4191-8E88-F1CE1333E72F-300x169.jpeg\" alt=\"\" width=\"300\" height=\"169\" \/><br \/>\n <div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>Panico in un condominio di via Consolarea Pompea, a Paradiso, a causa di un incendio sviluppatosi al pianoterra dello stabile. Il fumo ha invaso gli appartamenti dei piani soprastanti e quasi tutti gli occupanti li hanno dovuti abbandonare frettolosamente. Alcuni anziani sono rimasti per\u00f2 intrappolati in casa e sono dovuti intervenire i vigili del fuoco [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":39449,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[6],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2020\/01\/B2D01E57-3E92-4250-9141-3C2122E61334.jpeg","author_info":{"display_name":"Redazione","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redazione\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/39451"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=39451"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/39451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/39449"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=39451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=39451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=39451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}