{"id":3547,"date":"2017-06-27T15:18:13","date_gmt":"2017-06-27T13:18:13","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=3547"},"modified":"2017-06-27T15:18:13","modified_gmt":"2017-06-27T13:18:13","slug":"comprensivo-cali-spettacolo-con-i-bimbi-dellinfanzia","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2017\/06\/27\/comprensivo-cali-spettacolo-con-i-bimbi-dellinfanzia\/","title":{"rendered":"Comprensivo Cal\u00ec, spettacolo con i bimbi dell&#039;Infanzia"},"content":{"rendered":"<p>Linguaglossa &#8211; Le api&#8230; simbolo dell&#8217;operosit\u00e0 in tutti campi. Il messaggio parte dal piccolo centro etneo che pu\u00f2, comunque, essere considerato al passo coi tempi grazie al grande impegno dell&#8217;istituto comprensivo &#8220;Santo Cal\u00ec&#8221;.<br \/>\nIn questo contesto di importante impegno culturale si \u00e8 espresso al meglio lo staff della scuola dell&#8217;infanzia Sant&#8217;Antonio. Tante piccole api, rappresentate dai bravi bimbi dell&#8217;asilo, hanno dato vita, nello spiazzo dei &#8220;domenicani&#8221;, ad una rappresentazione che rester\u00e0 negli annali della scuola \u00e8, probabilmente, di tutto il comprensorio etneo. Dopo la tradizionale sfilata in paese, lo spettacolo ha preso vita in un palco attorniato dai genitori. Alla fine applausi per tutti come ad esempio le brave ed amorevoli insegnanti della scuola, spinte dalle rappresentanti di classe che sono state premiate per il loro costante impegno.<br \/>\nAlla fine applausi per tutti, anche per la inesauribile conduttrice, in un momento che ha rappresentato la fine di un anno scolastico indimenticabile per i tanti bimbi protagonisti della performance.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<p style=\"text-align: right;\"><strong>Mauro Romano<\/strong><div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Linguaglossa &#8211; Le api&#8230; simbolo dell&#8217;operosit\u00e0 in tutti campi. Il messaggio parte dal piccolo centro etneo che pu\u00f2, comunque, essere considerato al passo coi tempi grazie al grande impegno dell&#8217;istituto comprensivo &#8220;Santo Cal\u00ec&#8221;. In questo contesto di importante impegno culturale si \u00e8 espresso al meglio lo staff della scuola dell&#8217;infanzia Sant&#8217;Antonio. Tante piccole api, rappresentate [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3548,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[13,15],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2017\/06\/Linguaglossa-scuola-2.jpg","author_info":{"display_name":"Redazione","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redazione\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/3547"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=3547"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/3547\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/3548"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=3547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=3547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=3547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}