{"id":2864,"date":"2017-06-15T09:34:16","date_gmt":"2017-06-15T07:34:16","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=2864"},"modified":"2017-06-15T09:34:16","modified_gmt":"2017-06-15T07:34:16","slug":"castelmola-ecco-il-terzo-assessore-della-giunta","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2017\/06\/15\/castelmola-ecco-il-terzo-assessore-della-giunta\/","title":{"rendered":"Castelmola, ecco il terzo assessore della Giunta"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">\u00c8 Nicola Siligato il terzo assessore della Giunta del sindaco, Orlando Russo. Una nomination questa non ancora ufficiale ma che resta l&#8217;ipotesi pi\u00f9 plausibile dell'&#8221;Orlando Russo, bis&#8221;, dopo la netta affermazione, alle recenti amministrative, dell&#8217;unico candidato sindaco in lizza nella cittadina castelmolese. Appare tramontata, adesso, la candidatura &#8220;in gonnella&#8221; della neo eletta consigliere comunale, Rosanna D&#8217;Ambra , alla vice sindacatura, resta l&#8217;importante exploit elettorale dopo un risultato elettorale di peso. Per lei sono, quindi, \u00a0in programma incarichi di assoluto prestigio. Insomma un momento di riflessione da parte del sindaco Russo che, comunque, vuole dare un segnale di continuit\u00e0 amministrativa alla sua azione politica. Ed in questo contesto di sguardo al passato, l&#8217;incarico di numero due della casa municipale, resta di appannaggio di Angelo D&#8217;Agostino. Con grande esperienza politica che gli deriva da retaggi familiari, D&#8217;Agostino, si appresta alla preparazione al dopo Russo. Assessore designato, di intenso spessore culturale, rimane, Eleonora Cacopardo. Insomma un assetto questo che guarda alla tradizione del governo cittadino finora espresso, pensando, per\u00f2, ai tanti progetti che debbono essere realizzati. Tra i pianti di intervento da affrontare ad esempi, si trova la questione relativa all&#8217;assetto idrogeologico della contrada Mastrissa. Ed in tal senso va interpretata la nomination di Siligato espressione di quella zona del territorio ad alta espansione demografica. I componenti della lista sono stati gratificati dell&#8217;elettorato e tutti siederanno negli scranni del civico consesso e precisamente: Bartolomeo Alibrandi, \u00a0Fabio D&#8217;Allura, Rossana D&#8217;Ambra, Lisa Intelisano, Massimiliano Pizzolo, Giuseppa Raneri, Rosario Sterrantino, Massimo Turrisi ed anche gli assessori, Cacopardo ed Intelisano. In questi giorni l&#8217;operativa segretaria, Rossella Stornaiolo, convocher\u00e0 gli eletti per la prima riunione del civico consesso. <\/span><div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<p class=\"p1\" style=\"text-align: right;\"><strong><span class=\"s1\">Mauro Romano<\/span><\/strong><div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 Nicola Siligato il terzo assessore della Giunta del sindaco, Orlando Russo. Una nomination questa non ancora ufficiale ma che resta l&#8217;ipotesi pi\u00f9 plausibile dell&#8217;&#8221;Orlando Russo, bis&#8221;, dopo la netta affermazione, alle recenti amministrative, dell&#8217;unico candidato sindaco in lizza nella cittadina castelmolese. Appare tramontata, adesso, la candidatura &#8220;in gonnella&#8221; della neo eletta consigliere comunale, Rosanna [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2179,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[3],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2017\/06\/Castelmola-2.jpg","author_info":{"display_name":"Redazione","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redazione\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/2864"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=2864"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/2864\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/2179"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=2864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=2864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=2864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}