{"id":273360,"date":"2026-09-02T09:33:07","date_gmt":"2026-09-02T07:33:07","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=273360"},"modified":"2026-09-02T09:33:10","modified_gmt":"2026-09-02T07:33:10","slug":"partecipate-nomine-congelate-ci-sono-problemi","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2026\/09\/02\/partecipate-nomine-congelate-ci-sono-problemi\/","title":{"rendered":"Partecipate: nomine congelate, ci sono problemi"},"content":{"rendered":"\n<p>Le nomine avrebbero dovuto essere ufficializzate ad inizio settimana, ma pare che adesso tutto slitti alla fine della settimana. Se tutto va bene. Le indiscrezioni pubblicate dal nostro giornale hanno scatenato fibrillazioni all\u2019interno di \u201cSud chiama Nord\u201d, al punto che Cateno De Luca si \u00e8 visto costretto a bloccare le procedure. Si parla di aggiustamenti, ma pare che il problema sia serio. Ieri la rottura definitiva con il gruppo che fa riferimento all\u2019ex consigliere Dario Zante, calato nella lista \u201cDe Luca sindaco di Sicilia\u201d per le regionali, a sua insaputa. Dopo che gli era stata proposta una presidenza in una delle Partecipate comunali.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n\n\n\n<p>Voci di corridoio parlano di un aspro scontro verbale fra De Luca e l\u2019avvocato Salvatore Silvestro, il quale com\u2019\u00e8 noto ha indicato almeno 20 candidati alle scorse amministrative. Seppure il penalista non faccia politica \u00e8 chiaro ed evidente che rappresenti un punto di riferimento per il leader del partito di De Luca. A tal proposito, c\u2019\u00e8 da registrare la presa di distanze dell\u2019ex capogruppo del Pd al Consiglio comunale, Paolo David, il quale politicamente si era avvicinato a \u201cSud chiama Nord\u201d con un piccolo plotone di candidati.<div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n\n\n\n<p>David pare abbia sbattuto la porta dopo la scarsa considerazione che \u00e8 stata riservata al suo gruppo nel \u201cgioco\u201d delle nomine per le Partecipate.<\/p>\n\n\n\n<p>Cateno De Luca si trova per la prima volta in seria difficolt\u00e0, rispetto a delle scelte che accontentano qualcuno ma che scontentano una moltitudine di persone. Gli impegni assunti in campagna elettorale non possono essere mantenuti anche perch\u00e9 c\u2019\u00e8 la spada di Damocle del ricorso al TAR che paralizza l\u2019attivit\u00e0 politico-amministrativa del sindaco Federico Basile.<\/p>\n\n\n\n<p><strong>D. Gam.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le nomine avrebbero dovuto essere ufficializzate ad inizio settimana, ma pare che adesso tutto slitti alla fine della settimana. Se tutto va bene. Le indiscrezioni pubblicate dal nostro giornale hanno scatenato fibrillazioni all\u2019interno di \u201cSud chiama Nord\u201d, al punto che Cateno De Luca si \u00e8 visto costretto a bloccare le procedure. Si parla di aggiustamenti, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":261319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[19],"tags":[13710,14032,2972,14037,4098],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2026\/02\/IMG-20260214-WA0355-scaled.jpg","author_info":{"display_name":"Redazione","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redazione\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/273360"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=273360"}],"version-history":[{"count":1,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/273360\/revisions"}],"predecessor-version":[{"id":273361,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/273360\/revisions\/273361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/261319"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=273360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=273360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=273360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}