{"id":270777,"date":"2026-07-15T17:08:57","date_gmt":"2026-07-15T15:08:57","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2026\/07\/15\/automotive-urso-in-europa-siamo-al-collasso-non-ce-tempo-da-perdere\/"},"modified":"2026-07-15T17:08:57","modified_gmt":"2026-07-15T15:08:57","slug":"automotive-urso-in-europa-siamo-al-collasso-non-ce-tempo-da-perdere","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2026\/07\/15\/automotive-urso-in-europa-siamo-al-collasso-non-ce-tempo-da-perdere\/","title":{"rendered":"Automotive, Urso \u201cIn Europa siamo al collasso, non c\u2019\u00e8 tempo da perdere\u201d"},"content":{"rendered":"<div>ROMA (ITALPRESS) &#8211; <em>&#8220;La crisi dell&#8217;auto \u00e8 europea. L&#8217;epicentro del terremoto \u00e8 a Bruxelles, nel regime regolatorio del Green Deal che ci ha reso dipendenti dalla Cina. L&#8217;abbiamo detto fin dall&#8217;inizio, con responsabilit\u00e0 e chiarezza, qui e in Europa. Ora tanti in Europa condividono le nostre posizioni&#8221;.<\/em> Lo ha detto il ministro delle Imprese e del Made in Italy, <strong>Adolfo Urso<\/strong>, nel corso del Question Time alla Camera.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<p><em>&#8220;Proprio stamattina abbiamo con il ministro francese dell&#8217;Industria, Martin, individuato una posizione comune che posso sintetizzare con: neutralit\u00e0 tecnologica e Made in Europe. Pi\u00f9 flessibilit\u00e0 tecnologica e pi\u00f9 componenti locali<\/em> &#8211; ha aggiunto Urso -. <em>Speriamo di coinvolgere a breve anche la Germania. Non c&#8217;\u00e8 tempo da perdere, perch\u00e8 come dimostrano gli annunci drammatici che si susseguono in Europa sulla chiusura di stabilimenti e licenziamenti, siamo al collasso. Sembra un bollettino di guerra, con un impatto negativo anche sulla nostra componentistica che produce per le case automobilistiche tedesche&#8221;.<\/em><div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n<p>&#8211; Foto IPA Agency &#8211;<\/p>\n<p>(ITALPRESS).<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; &#8220;La crisi dell&#8217;auto \u00e8 europea. L&#8217;epicentro del terremoto \u00e8 a Bruxelles, nel regime regolatorio del Green Deal che ci ha reso dipendenti dalla Cina. L&#8217;abbiamo detto fin dall&#8217;inizio, con responsabilit\u00e0 e chiarezza, qui e in Europa. Ora tanti in Europa condividono le nostre posizioni&#8221;. Lo ha detto il ministro delle Imprese e [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":270778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[446],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2026\/07\/20260715_2666.jpg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/270777"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=270777"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/270777\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/270778"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=270777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=270777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=270777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}