{"id":270731,"date":"2026-07-15T01:08:57","date_gmt":"2026-07-14T23:08:57","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2026\/07\/15\/la-spagna-piega-la-francia-2-0-e-vola-in-finale-ai-mondiali\/"},"modified":"2026-07-15T01:08:57","modified_gmt":"2026-07-14T23:08:57","slug":"la-spagna-piega-la-francia-2-0-e-vola-in-finale-ai-mondiali","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2026\/07\/15\/la-spagna-piega-la-francia-2-0-e-vola-in-finale-ai-mondiali\/","title":{"rendered":"La Spagna piega la Francia 2-0 e vola in finale ai Mondiali"},"content":{"rendered":"<div>DALLAS (STATI UNITI) (ITALPRESS) &#8211; La Spagna \u00e8 la prima finalista dei Mondiali. Non c&#8217;\u00e8 storia a Dallas, dove le Furie Rosse stendono per 2-0 una Francia, in versione opaca. Decisivi il rigore siglato da Oyarzabal nel primo tempo e il raddoppio di Pedro Porro nella ripresa, che riportano la selezione iberica all&#8217;ultimo atto della competizione per la prima volta dal 2010, quando aveva poi conquistato la coppa.<br \/>\nRitmi bassi in avvio di gara, con la Spagna a mantenere il possesso senza per\u00f2 rendersi troppo pericolosa, con alcuni cross inoffensivi per Maignan e compagni. Alla prima sbavatura, per\u00f2, le furie rosse ne approfittano. Lamine Yamal si getta verso un pallone vagante sul lato destro dell&#8217;area, Digne commette un&#8217;ingenuit\u00e0 e colpisce il giovane del Barcellona: Barton indica senza dubbi il dischetto. Dagli undici metri si presenta Oyarzabal, che batte il portiere avversario. I Bleus accusano il colpo, mentre la Spagna prova a colpire ancora sull&#8217;onda dell&#8217;entusiasmo. Al 38&#8242; azione rapida e spettacolare degli uomini di de la Fuente, che si conclude con la deviazione provvidenziale in area di Upamecano. Si va all&#8217;intervallo sul risultato di 0-1.<br \/>\nDue i cambi di Deschamps nei primi minuti della ripresa. Gli iberici, per\u00f2, cominciano in avanti anche il secondo tempo, raddoppiando al 58&#8242; dopo alcuni tentativi. Porro sfonda accentrandosi dalla destra, scambia con Olmo e trafigge Maignan con un gran destro per il raddoppio spagnolo. Poco dopo, Yamal insacca dopo una giocata di classe in area, mettendo a sedere un difensore avversario e superando Maignan; si alza per\u00f2 la bandierina del guardalinee per un leggerissimo fuorigioco del classe 2007. La Francia prova a reagire, ma manca di cinismo in pi\u00f9 occasioni come all&#8217;81&#8217;, quando Dou\u00e8 raccoglie un pallone a 20 metri dalla porta, dopo un&#8217;uscita fuori area di Unai Simon su Mbapp\u00e8, calciando per\u00f2 sul portiere avversario. Il forcing dei Bleus nel finale serve a poco: la Spagna vola in finale, dove attende la vincitrice di Inghilterra-Argentina. Per i transalpini la finalina per il terzo posto come magra consolazione.<br \/>\n&#8211; foto Ipa Agency &#8211;<br \/>\n(ITALPRESS).<\/div>\n<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p><div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>DALLAS (STATI UNITI) (ITALPRESS) &#8211; La Spagna \u00e8 la prima finalista dei Mondiali. Non c&#8217;\u00e8 storia a Dallas, dove le Furie Rosse stendono per 2-0 una Francia, in versione opaca. Decisivi il rigore siglato da Oyarzabal nel primo tempo e il raddoppio di Pedro Porro nella ripresa, che riportano la selezione iberica all&#8217;ultimo atto della [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":270732,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[446],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2026\/07\/20260714_3171.jpg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/270731"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=270731"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/270731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/270732"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=270731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=270731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=270731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}