{"id":266887,"date":"2026-05-13T21:09:00","date_gmt":"2026-05-13T19:09:00","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2026\/05\/13\/agli-internazionali-ditalia-si-celebra-la-cucina-italiana-patrimonio-unesco\/"},"modified":"2026-05-13T21:09:00","modified_gmt":"2026-05-13T19:09:00","slug":"agli-internazionali-ditalia-si-celebra-la-cucina-italiana-patrimonio-unesco","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2026\/05\/13\/agli-internazionali-ditalia-si-celebra-la-cucina-italiana-patrimonio-unesco\/","title":{"rendered":"Agli Internazionali d\u2019Italia si celebra la cucina italiana patrimonio UNESCO"},"content":{"rendered":"<div>ROMA (ITALPRESS) &#8211; Gli Internazionali BNL d&#8217;Italia hanno ospitato una serata dedicata alla celebrazione della cucina italiana<br \/>patrimonio UNESCO, simbolo dell&#8217;identit\u00e0 nazionale, della qualit\u00e0 agroalimentare e del legame tra tradizione e territori.<br \/>Nel corso dell&#8217;evento, promosso dal Ministero dell&#8217;Agricoltura, della Sovranit\u00e0 alimentare e delle Foreste insieme a ISMEA, il Ministro Francesco Lollobrigida ha premiato quattro protagonisti del mondo dell&#8217;informazione e uno chef che si \u00e8 distinto per la sua interpretazione della cultura gastronomica italiana.<br \/>Con il loro lavoro, hanno contribuito a valorizzare il settore agroalimentare e le eccellenze italiane, accompagnando con il loro racconto il percorso che ha portato la cucina italiana al prestigioso riconoscimento UNESCO.<br \/>Nel corso della serata \u00e8 stato inoltre sottolineato il forte legame tra corretta alimentazione, sport, qualit\u00e0 delle produzioni italiane e promozione del Made in Italy, evidenziando il ruolo centrale dell&#8217;informazione nella diffusione della cultura del cibo e nella valorizzazione dei territori.<br \/>&#8220;La cucina italiana \u00e8 diventata patrimonio UNESCO anche grazie a chi, ogni giorno, ne racconta il valore, le tradizioni, il legame con i territori e con il nostro sistema agricolo. Questo riconoscimento appartiene all&#8217;Italia intera e a tutti coloro che hanno contribuito a promuovere nel mondo la qualit\u00e0 delle nostre<br \/>eccellenze agroalimentari&#8221;, ha dichiarato il Ministro Francesco Lollobrigida.<br \/>Sono stati premiati: Roberto Napoletano, direttore de Il Messaggero, per aver colto fin dal primo istante il valore simbolico ed economico del riconoscimento UNESCO della cucina italiana e per aver contribuito, attraverso la sua<br \/>direzione, a valorizzare il ruolo che l&#8217;agricoltura italiana ha avuto anche nei contesti internazionali; Antonio Preziosi, direttore del TG2, per aver raccontato costantemente il percorso della candidatura UNESCO della cucina italiana e per il suo impegno nel rappresentare la complessit\u00e0 del mondo agricolo e<br \/>le sue connessioni con ristorazione, turismo ma soprattutto educazione e sociale; Anna Scafuri, cronista del TG1, per il suo impegno pluridecennale nel racconto dell&#8217;agricoltura italiana<br \/>e per aver precorso i tempi attraverso rubriche dedicate alle eccellenze enogastronomiche e ai territori; Tetsuro Akanegakubo del The Shakai Shimpo, per aver scelto l&#8217;Italia come luogo di vita e di racconto, contribuendo a diffondere nel mondo, con autenticit\u00e0 e passione, la cultura e le eccellenze italiane;<br \/>Andrea Aprea, chef, per aver valorizzato nella sua cucina la tradizione e l&#8217;innovazione, trasformando la memoria dei sapori e delle tradizioni italiane in una proposta contemporanea riconosciuta a livello internazionale.<br \/>Alla serata hanno partecipato, tra gli altri, il Ministro del Turismo Gianmarco Mazzi, il presidente di ISMEA Livio Proietti, il direttore generale di ISMEA Sergio Marchi, il presidente del CREA Andrea Rocchi, il direttore generale Maria Chiara Zaganelli, insieme a rappresentanti delle istituzioni, del mondo<br \/>agricolo, dell&#8217;informazione, dello sport e della filiera agroalimentare italiana.<br \/>&#8220;La candidatura UNESCO della cucina italiana \u00e8 stata un grande lavoro collettivo che ha coinvolto istituzioni, imprese, territori, mondo agricolo e informazione. Continueremo a promuovere nel mondo il valore del nostro modello alimentare, della qualit\u00e0 italiana e della cultura che rende unica la nostra Nazione&#8221;, ha concluso il Ministro Lollobrigida.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<p>&#8211; Foto mec\/Italpress &#8211;<div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n<p>(ITALPRESS).<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; Gli Internazionali BNL d&#8217;Italia hanno ospitato una serata dedicata alla celebrazione della cucina italianapatrimonio UNESCO, simbolo dell&#8217;identit\u00e0 nazionale, della qualit\u00e0 agroalimentare e del legame tra tradizione e territori.Nel corso dell&#8217;evento, promosso dal Ministero dell&#8217;Agricoltura, della Sovranit\u00e0 alimentare e delle Foreste insieme a ISMEA, il Ministro Francesco Lollobrigida ha premiato quattro protagonisti del [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":266888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[446],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2026\/05\/20260513_2744.jpg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/266887"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=266887"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/266887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/266888"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=266887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=266887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=266887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}