{"id":266847,"date":"2026-05-13T11:08:54","date_gmt":"2026-05-13T09:08:54","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2026\/05\/13\/hantavirus-negativi-i-test-analizzati-a-milano-e-allo-spallanzani\/"},"modified":"2026-05-13T11:08:54","modified_gmt":"2026-05-13T09:08:54","slug":"hantavirus-negativi-i-test-analizzati-a-milano-e-allo-spallanzani","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2026\/05\/13\/hantavirus-negativi-i-test-analizzati-a-milano-e-allo-spallanzani\/","title":{"rendered":"Hantavirus, negativi i test analizzati a Milano e allo Spallanzani"},"content":{"rendered":"<div>ROMA (ITALPRESS) &#8211; Il Ministero della Salute informa che gli accertamenti virologici eseguiti ieri a Milano sul turista britannico rintracciato e posto in quarantena perch\u00e8 si trovava a bordo del volo Sant&#8217;Elena-Johannesburg hanno dato esito negativo. Cos\u00ec come negativo \u00e8 il test dell&#8217;accompagnatore che viaggiava con lui in Italia.<br \/>Sono altres\u00ec negativi i test effettuati sul giovane calabrese che si trova in isolamento fiduciario e sulla turista che \u00e8 stata ricoverata a Messina per polmonite e che proviene da una zona endemica dell&#8217;Argentina. I campioni di entrambi sono stati analizzati allo Spallanzani di Roma.<br \/>Il Ministero ricorda che il rischio connesso al virus resta molto basso in Europa e, dunque, anche in Italia.<br \/>-foto Ipa Agency-<br \/>(ITALPRESS).<\/div>\n<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p><div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; Il Ministero della Salute informa che gli accertamenti virologici eseguiti ieri a Milano sul turista britannico rintracciato e posto in quarantena perch\u00e8 si trovava a bordo del volo Sant&#8217;Elena-Johannesburg hanno dato esito negativo. Cos\u00ec come negativo \u00e8 il test dell&#8217;accompagnatore che viaggiava con lui in Italia.Sono altres\u00ec negativi i test effettuati sul [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":266848,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[446],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2026\/05\/20260513_0129.jpg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/266847"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=266847"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/266847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/266848"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=266847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=266847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=266847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}