{"id":263613,"date":"2026-03-21T10:59:55","date_gmt":"2026-03-21T09:59:55","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=263613"},"modified":"2026-03-21T10:59:56","modified_gmt":"2026-03-21T09:59:56","slug":"lutto-si-e-spento-lex-capo-della-mobile-franco-barbagallo","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2026\/03\/21\/lutto-si-e-spento-lex-capo-della-mobile-franco-barbagallo\/","title":{"rendered":"Lutto, si \u00e8 spento l&#8217;ex capo della Mobile Franco Barbagallo"},"content":{"rendered":"\n<p>Si \u00e8 spento all&#8217;et\u00e0 di 76 anni l&#8217;ex capo della Squadra Mobile di Messina, Franco Barbagallo. Alto dirigente della Polizia di Stato, ha prestato servizio, fra l&#8217;altro nella citt\u00e0 dello Stretto.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n\n\n\n<p>I funerali saranno celebrati luned\u00ec 23 marzo 2026, alle ore, alla chiesa Cattedrale di piazza Duomo.<div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n\n\n\n<p>Alla famiglia, le condoglianze della nostra redazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 spento all&#8217;et\u00e0 di 76 anni l&#8217;ex capo della Squadra Mobile di Messina, Franco Barbagallo. Alto dirigente della Polizia di Stato, ha prestato servizio, fra l&#8217;altro nella citt\u00e0 dello Stretto. I funerali saranno celebrati luned\u00ec 23 marzo 2026, alle ore, alla chiesa Cattedrale di piazza Duomo. Alla famiglia, le condoglianze della nostra redazione.<\/p>\n","protected":false},"author":2,"featured_media":263614,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[5],"tags":[13097,13096,3031],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2026\/03\/654284815_26358219513811195_6362190180780023940_n.jpg","author_info":{"display_name":"Redazione","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redazione\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/263613"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=263613"}],"version-history":[{"count":1,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/263613\/revisions"}],"predecessor-version":[{"id":263615,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/263613\/revisions\/263615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/263614"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=263613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=263613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=263613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}