{"id":263482,"date":"2026-03-19T15:48:26","date_gmt":"2026-03-19T14:48:26","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2026\/03\/19\/incidente-mortale-nel-ragusano-sulla-sp-46-ispica-pozzallo-muore-un-camionista-di-71-anni\/"},"modified":"2026-03-19T15:48:26","modified_gmt":"2026-03-19T14:48:26","slug":"incidente-mortale-nel-ragusano-sulla-sp-46-ispica-pozzallo-muore-un-camionista-di-71-anni","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2026\/03\/19\/incidente-mortale-nel-ragusano-sulla-sp-46-ispica-pozzallo-muore-un-camionista-di-71-anni\/","title":{"rendered":"Incidente mortale nel Ragusano sulla SP 46 Ispica-Pozzallo, muore un camionista di 71 anni"},"content":{"rendered":"<div>\n<p>RAGUSA (ITALPRESS) \u2013 <strong>Incidente mortale sulla SP 46 Ispica \u2013 Pozzallo, nel Ragusano.<\/strong> La vittima \u00e8 un <strong>camionista, di 71 anni.<\/strong> Viaggiava a bordo di un autocarro che si \u00e8 scontrato con un\u2019auto. A causa del sinistro il mezzo pesante \u00e8 uscito di strada ed il conducente \u00e8 deceduto.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<p>L\u2019uomo, residente a Ispica, \u00e8 stato estratto dalle lamiere dai vigili del fuoco, intervenuto sul posto. Per lui non c\u2019\u00e8 stato nulla da fare. Il conducente dell\u2019auto, una Peugeot, \u00e8 stato trasportato all\u2019ospedale di Modica. Sul posto per i rilievi di competenza i Carabinieri di Pozzallo e Modica oltre alle ambulanze del 118.<div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n<p>-Foto Vigili del Fuoco-<br \/>\n(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>RAGUSA (ITALPRESS) \u2013 Incidente mortale sulla SP 46 Ispica \u2013 Pozzallo, nel Ragusano. La vittima \u00e8 un camionista, di 71 anni. Viaggiava a bordo di un autocarro che si \u00e8 scontrato con un\u2019auto. A causa del sinistro il mezzo pesante \u00e8 uscito di strada ed il conducente \u00e8 deceduto. L\u2019uomo, residente a Ispica, \u00e8 stato [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":263483,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[2449],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-14.27.32.jpeg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/263482"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=263482"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/263482\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/263483"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=263482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=263482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=263482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}