{"id":258313,"date":"2026-01-06T18:06:45","date_gmt":"2026-01-06T17:06:45","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2026\/01\/06\/il-como-vince-anche-a-pisa-e-continua-a-sognare-leuropa\/"},"modified":"2026-01-06T19:29:38","modified_gmt":"2026-01-06T18:29:38","slug":"il-como-vince-anche-a-pisa-e-continua-a-sognare-leuropa","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2026\/01\/06\/il-como-vince-anche-a-pisa-e-continua-a-sognare-leuropa\/","title":{"rendered":"Il Como vince anche a Pisa e continua a sognare l\u2019Europa"},"content":{"rendered":"<div>PISA (ITALPRESS) &#8211; Il Como espugna anche l&#8217;Arena Garibaldi e centra la terza vittoria consecutiva: 3-0 al Pisa, con i lariani che continuano a sognare un posto in Europa. Decidono la doppietta di Anastasios Douvikas e un gol di Maximo Perrone. La formazione ospite prova a partire subito forte, costruendo la prima occasione al 4&#8242; con Nico Paz, la cui conclusione su schema da corner viene respinta da Semper. Al 16&#8242; l&#8217;argentino perde un brutto pallone e Nzola prova ad approfittarne, ma il suo tiro viene respinto da Ramon. Quattro minuti pi\u00f9 tardi i nerazzurri vanno vicini alla rete del vantaggio con Tramoni che, su assist di Nzola, sfiora il palo con un insidioso destro. Intorno alla mezz&#8217;ora il Como torna a farsi vedere in avanti con il solito Nico Paz che, lanciato da Da Cunha, trova nuovamente l&#8217;opposizione di un attento Semper. Al 41&#8242; Nzola penetra da solo in area di rigore, ma al momento della conclusione sbaglia tutto, sciupando una buona opportunit\u00e0. A pochi secondi dall&#8217;intervallo Ramon rimedia una pesante ammonizione, che lo costringer\u00e0 a saltare la prossima gara contro il Bologna. Nella ripresa il Pisa torna in campo con maggiore convinzione e al 48&#8242; Tramoni serve Piccinini, il quale prova ad impensierire Butez con un tiro ribattuto dallo stesso portiere. Al 52&#8242; l&#8217;asse Tramoni-Piccinini si riaccende con un nuovo tentativo del centrocampista che, anche in questo caso, viene arginato da Butez. Dopo un momento di sbandamento, gli uomini di Cesc Fabregas tornano a spingere con decisione, tanto che al 68&#8242; trovano la rete del vantaggio con un tiro dal limite dell&#8217;area di Maximo Perrone. I toscani accusano il colpo e prestano il fianco al contropiede avversario: al 76&#8242;, infatti, Anastasios Douvikas riceve palla da Jesus Rodriguez, entra in area e batte Semper con un diagonale. Nonostante un uno-due pesantissimo da digerire, il Pisa all&#8217;85&#8217; ha una grande chance per riaprire la partita con un calcio da rigore conquistato da Leris, che subisce fallo da Caqueret: sul dischetto si presenta Nzola, che calcia male e agevola la parata di Butez. In pieno recupero anche i lariani guadagnano un penalty in seguito ad un fallo di Coppola su Douvikas: quest&#8217;ultimo dagli undici metri spiazza Semper e, con la sua personale doppietta, fissa il punteggio sul definitivo 3-0. In virt\u00f9 di questo successo il Como vola a 33 punti in classifica, agganciando provvisoriamente Roma e Juve, mentre il Pisa resta in zona retrocessione a quota 12. I lombardi torneranno in campo gi\u00e0 sabato pomeriggio per il big-match del Sinigaglia contro il Bologna; i toscani, dal loro canto, saranno ospiti dell&#8217;Udinese al Bluenergy Stadium.<br \/>&#8211; foto Image &#8211;<br \/>(ITALPRESS).<\/div>\n<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p><div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>PISA (ITALPRESS) &#8211; Il Como espugna anche l&#8217;Arena Garibaldi e centra la terza vittoria consecutiva: 3-0 al Pisa, con i lariani che continuano a sognare un posto in Europa. Decidono la doppietta di Anastasios Douvikas e un gol di Maximo Perrone. La formazione ospite prova a partire subito forte, costruendo la prima occasione al 4&#8242; [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":258314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[10,446,9],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2026\/01\/20260106_0640.jpg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/258313"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=258313"}],"version-history":[{"count":1,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/258313\/revisions"}],"predecessor-version":[{"id":258322,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/258313\/revisions\/258322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/258314"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=258313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=258313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=258313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}