{"id":242193,"date":"2025-06-06T12:09:27","date_gmt":"2025-06-06T10:09:27","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2025\/06\/06\/arrestato-in-belgio-latitante-albanese-ricercato-da-dda-di-bari\/"},"modified":"2025-06-06T12:09:27","modified_gmt":"2025-06-06T10:09:27","slug":"arrestato-in-belgio-latitante-albanese-ricercato-da-dda-di-bari","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2025\/06\/06\/arrestato-in-belgio-latitante-albanese-ricercato-da-dda-di-bari\/","title":{"rendered":"Arrestato in Belgio latitante albanese ricercato da Dda di Bari"},"content":{"rendered":"<div>ROMA (ITALPRESS) &#8211; E&#8217; stato consegnato alle autorit\u00e0 italiane un cittadino albanese, arrestato ad Arlon (Belgio) il 21 maggio scorso da personale del <strong>FAST Team belga<\/strong>, nell&#8217;ambito dell&#8217;operazione internazionale &#8220;URA&#8221;.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<p>L&#8217;operazione, coordinata dalla <strong>DIA di Bari<\/strong> in sinergia con le autorit\u00e0 albanesi, si inserisce in una pi\u00f9 ampia indagine che ha gi\u00e0 portato all&#8217;emissione di 52 ordinanze di custodia cautelare concesse dal<strong> GIP di Bari<\/strong> su richiesta della locale Direzione Distrettuale Antimafia (accertamento compiuto nella fase delle indagini preliminari che necessita della successiva verifica processuale nel contraddittorio con la difesa).<div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n<p>La cattura del cittadino albanese \u00e8 avvenuta grazie al determinante contributo del Servizio per la Cooperazione Internazionale di polizia e la rete europea ENFAST (European Network of Fugitive Active Search Teams), attraverso la collaborazione tra i FAST Team italiano, belga e lussemburghese.<\/p>\n<p>L&#8217;attivit\u00e0 investigativa transnazionale, finalizzata alla localizzazione e alla cattura dell&#8217;uomo, ha permesso al FAST Team del Lussemburgo di effettuare una attivit\u00e0 di pedinamento fino ai confini con il Belgio, dove il ricercato \u00e8 stato rintracciato la sera del 20 maggio. L&#8217;arrestato \u00e8 stato preso in consegna dalle autorit\u00e0 belghe e oggi formalmente consegnato all&#8217;Italia.<\/p>\n<p>&#8211; Foto Ufficio stampa Polizia di Stato &#8211;<\/p>\n<p>(ITALPRESS)<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; E&#8217; stato consegnato alle autorit\u00e0 italiane un cittadino albanese, arrestato ad Arlon (Belgio) il 21 maggio scorso da personale del FAST Team belga, nell&#8217;ambito dell&#8217;operazione internazionale &#8220;URA&#8221;. L&#8217;operazione, coordinata dalla DIA di Bari in sinergia con le autorit\u00e0 albanesi, si inserisce in una pi\u00f9 ampia indagine che ha gi\u00e0 portato all&#8217;emissione di [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":242194,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[446],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2025\/06\/20250606_0074.jpg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/242193"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=242193"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/242193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/242194"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=242193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=242193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=242193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}