{"id":231229,"date":"2025-03-09T14:15:44","date_gmt":"2025-03-09T13:15:44","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2025\/03\/09\/incendio-nella-notte-a-palermo-una-persona-ustionata\/"},"modified":"2025-03-09T14:15:44","modified_gmt":"2025-03-09T13:15:44","slug":"incendio-nella-notte-a-palermo-una-persona-ustionata","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2025\/03\/09\/incendio-nella-notte-a-palermo-una-persona-ustionata\/","title":{"rendered":"Incendio nella notte a Palermo, una persona ustionata"},"content":{"rendered":"<div>\n<p>PALERMO (ITALPRESS) \u2013 <strong>Squadre dei Vigili del Fuoco di Palermo<\/strong> sono intervenute questa notte dalle ore 4.00 circa per un <strong>incendio di un abitazione posto al quinto ed ultimo piano di una palazzina in via Sabratha<\/strong> nel capoluogo siciliano. Una persona \u00e8 stata coinvolta dall\u2019incendio, riportando ustioni e intossicazione da fumi della combustione.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<p>Le altre persone residenti nella palazzina sono state fatte evacuare e non risultano feriti. L\u2019incendio \u00e8 stato completamente spento intorno alle ore 6, e i residenti sono stati fatti rientrare nelle loro case.<div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n<p>-Foto Vigili del Fuoco Palermo-<br \/>\n(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>PALERMO (ITALPRESS) \u2013 Squadre dei Vigili del Fuoco di Palermo sono intervenute questa notte dalle ore 4.00 circa per un incendio di un abitazione posto al quinto ed ultimo piano di una palazzina in via Sabratha nel capoluogo siciliano. Una persona \u00e8 stata coinvolta dall\u2019incendio, riportando ustioni e intossicazione da fumi della combustione. Le altre [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":231230,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[2449],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2025\/03\/Vigili-del-Fuoco-Palermo.jpeg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/231229"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=231229"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/231229\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/231230"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=231229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=231229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=231229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}