{"id":228723,"date":"2025-02-14T23:05:39","date_gmt":"2025-02-14T22:05:39","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2025\/02\/14\/abodi-chiude-a-malago-legge-non-prevede-quarto-mandato\/"},"modified":"2025-02-14T23:05:39","modified_gmt":"2025-02-14T22:05:39","slug":"abodi-chiude-a-malago-legge-non-prevede-quarto-mandato","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2025\/02\/14\/abodi-chiude-a-malago-legge-non-prevede-quarto-mandato\/","title":{"rendered":"Abodi chiude a Malag\u00f2 \u201cLegge non prevede quarto mandato\u201d"},"content":{"rendered":"<div>ROMA (ITALPRESS) &#8211; &#8220;Malag\u00f2 finisce con questo mandato. Non c&#8217;\u00e8 il rinnovo perch\u00e8 la legge non lo prevede&#8221;. Parola di Andrea Abodi, ministro per lo sport e i giovani, che a &#8216;Casa Sanrem\u00f2 chiude alla possibilit\u00e0 di un quarto mandato, o quantomeno di una proroga fino alla conclusione di Milano-Cortina 2026, per il numero 1 dello sport italiano. Stando alla legge attuale, Giovanni Malag\u00f2 non pu\u00f2 fare pi\u00f9 di tre mandati a differenza dei presidenti della Federazioni sportive. Ma allo stesso tempo la vicinanza temporale con le Olimpiadi invernali (in programma dal 6 al 22 febbraio 2026) aveva spinto pi\u00f9 di qualcuno ad ipotizzare una proroga del mandato per consentire all&#8217;attuale presidente di rivestire nel corso dei Giochi il doppio ruolo di numero 1 della Fondazione Milano-Cortina e del Comitato olimpico nazionale. Il tempo per\u00f2 stringe. Malag\u00f2 lo scorso settembre aveva indicato la fine del mese di gennaio come &#8220;una data ragionevole&#8221; entro la quale capire se potr\u00e0 ripresentarsi o meno. Gennaio \u00e8 passato, le elezioni del Coni si terranno il prossimo 26 giugno e il termine ultimo per presentare la candidatura \u00e8 il 5 giugno. Segnali dal Governo ce ne sono stati, quello di Abodi \u00e8 l&#8217;ultimo, ma pochi giorni fa era arrivato anche un assist del vicepremier e ministro dei trasporti, Matteo Salvini, che si era detto favorevole alla possibilit\u00e0 che Malag\u00f2 &#8220;arrivi ad accompagnare le Olimpiadi, quindi fino alla loro conclusione nella primavera 2026&#8221;. All&#8217;orizzonte ci sono proprio i Giochi e l&#8217;altro tema caldo \u00e8 quello dei ritardi, ma Abodi si dice fiducioso. &#8220;Li abbiamo trovati pi\u00f9 allora che riscontrati oggi &#8211; ha detto a margine di un evento sulla Liguria Regione europea dello sport 2025 -. Questi due anni e mezzo sono serviti per accelerare. Io ho sempre detto che il tempo non ci \u00e8 stato amico e adesso abbiamo iniziato a familiarizzare con il tempo: siamo convinti di arrivare pronti quando dovremo essere pronti&#8221;.<br \/>&#8211; Foto Ipa Agency &#8211;<br \/>(ITALPRESS).<\/div>\n<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p><div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; &#8220;Malag\u00f2 finisce con questo mandato. Non c&#8217;\u00e8 il rinnovo perch\u00e8 la legge non lo prevede&#8221;. Parola di Andrea Abodi, ministro per lo sport e i giovani, che a &#8216;Casa Sanrem\u00f2 chiude alla possibilit\u00e0 di un quarto mandato, o quantomeno di una proroga fino alla conclusione di Milano-Cortina 2026, per il numero 1 [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":228724,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[446],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2025\/02\/20250214_2647.jpg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/228723"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=228723"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/228723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/228724"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=228723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=228723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=228723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}