{"id":21908,"date":"2018-07-13T15:40:16","date_gmt":"2018-07-13T13:40:16","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=21908"},"modified":"2018-07-13T15:40:16","modified_gmt":"2018-07-13T13:40:16","slug":"danza-sportiva","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2018\/07\/13\/danza-sportiva\/","title":{"rendered":"Danza sportiva, titolo nazionale per la messinese Santina Boncordo"},"content":{"rendered":"<p style=\"text-align: justify\">Una quasi 23enne messinese (proprio venerd\u00ec prossimo, 20 luglio,\u00a0festegger\u00e0 il compleanno) sale sul podio nazionale pi\u00f9 alto dei campionati italiani 2018 della FIDS (Federazione Italiana Danza Sportiva&#8221;. Nei giorni scorsi <strong>Santina Boncordo<\/strong> ha centrato, in quel di Rimini &#8211; sotto lo sguardo di Carla Fracci, Kleidi e Garrison Rochelle &#8211; il primo posto nella &#8220;<em>jazz dance<\/em>&#8220;, categoria 16 OL, classe C. In precedenza aveva superato sia la fasi provinciali che regionali.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<p style=\"text-align: justify\">Una vita dedicata alla danza da Santina che, dopo il diploma in danza presso la &#8220;Dance Arts International&#8221; di Milano, si \u00e8 laureata prima in Scienze Motorie e Sportive (in questo caso si \u00e8 anche specializzata) e poi in Fisioterapia. In pi\u00f9 da 14 anni \u00e8 titolare della scuola di danza &#8220;Bolero&#8221; di messina, sita in via Comunale n 82 a Bordonaro.<div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una quasi 23enne messinese (proprio venerd\u00ec prossimo, 20 luglio,\u00a0festegger\u00e0 il compleanno) sale sul podio nazionale pi\u00f9 alto dei campionati italiani 2018 della FIDS (Federazione Italiana Danza Sportiva&#8221;. Nei giorni scorsi Santina Boncordo ha centrato, in quel di Rimini &#8211; sotto lo sguardo di Carla Fracci, Kleidi e Garrison Rochelle &#8211; il primo posto nella &#8220;jazz [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":21910,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[8],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2018\/07\/Boncordo-2-1.jpg","author_info":{"display_name":"redsport","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redsport\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/21908"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=21908"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/21908\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/21910"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=21908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=21908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=21908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}