{"id":218919,"date":"2024-11-19T09:26:04","date_gmt":"2024-11-19T08:26:04","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=218919"},"modified":"2024-11-19T09:26:05","modified_gmt":"2024-11-19T08:26:05","slug":"taormina-ospita-il-food-expo-2024","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2024\/11\/19\/taormina-ospita-il-food-expo-2024\/","title":{"rendered":"Taormina ospita il &#8220;Food Expo 2024&#8221;"},"content":{"rendered":"\n<p>Torna il &#8220;Taormina Food Expo 2024&#8221;, dal 21 al 24 novembre, presso il Palazzo dei congressi della citt\u00e0 ionica. L\u2019evento, giunto alla sua terza edizione, \u00e8 organizzato dalla Cna Sicilia, con il contributo dell\u2019Assessorato Regionale dell\u2019Agricoltura, dello Sviluppo Rurale e della Pesca Mediterranea, il patrocinio oneroso dell\u2019Assessorato Regionale al Turismo ed non oneroso del Comune di Taormina.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n\n\n\n<p>Una kermesse che vedr\u00e0 la partecipazione di pi\u00f9 di 50 aziende, organizzazioni e personalit\u00e0 del settore, delle istituzioni locali, nazionali ed internazionali, tra cui la Malta Food Agency e il ministro dell\u2019agricoltura maltese, Anton Refalo, e il presidente del Parlamento maltese, Angelo Farrugia. Saranno quattro giorni dedicati alle eccellenze dell\u2019agroalimentare mediterraneo, scanditi da dibattiti, show cooking (animati da una ricca delegazione di chef maltesi insieme agli chef siciliani della Unione Regionale Cuochi Siciliani presieduta da Rosario Seidita), degustazioni e incontri b2b tra imprenditori e buyers. Quest\u2019ultimi sono organizzati dall\u2019Ufficio Promozione e Mercato Internazionale della CNA Nazionale e dall\u2019agenzia ITA\/Ice. L\u2019inaugurazione si terr\u00e0 gioved\u00ec 21, alle ore 15.30, alla presenza delle autorit\u00e0. <div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n\n\n\n<p>\u201cNon solo una vetrina espositiva &#8211; dichiarano Tindaro Germanelli e Enzo Di Stefano, rispettivamente responsabile e presidente della Cna agroalimentare Sicilia &#8211; ma un momento di scambio e crescita per tutti i partecipanti, all\u2019interno del quale fanno da padrone le eccellenze enogastronomiche, con un focus sui prodotti a chilometro zero, le produzioni siciliane come formaggi, vini, lievitati, conserve e oli di alta qualit\u00e0. Un vero e proprio contenitore culinario e culturale, dove assistere tra le tante cose alla presentazione di libri e dove si terr\u00e0 un appuntamento sul centenario del maestro Camilleri, che ricorrer\u00e0 nel 2025\u201d. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torna il &#8220;Taormina Food Expo 2024&#8221;, dal 21 al 24 novembre, presso il Palazzo dei congressi della citt\u00e0 ionica. L\u2019evento, giunto alla sua terza edizione, \u00e8 organizzato dalla Cna Sicilia, con il contributo dell\u2019Assessorato Regionale dell\u2019Agricoltura, dello Sviluppo Rurale e della Pesca Mediterranea, il patrocinio oneroso dell\u2019Assessorato Regionale al Turismo ed non oneroso del Comune [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":218920,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[3],"tags":[10604,10885],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2024\/11\/ART_-526.jpg","author_info":{"display_name":"Redazione","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redazione\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/218919"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=218919"}],"version-history":[{"count":1,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/218919\/revisions"}],"predecessor-version":[{"id":218921,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/218919\/revisions\/218921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/218920"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=218919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=218919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=218919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}