{"id":201741,"date":"2024-06-19T11:23:40","date_gmt":"2024-06-19T09:23:40","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=201741"},"modified":"2024-06-19T11:23:42","modified_gmt":"2024-06-19T09:23:42","slug":"maturita-2024-ecco-tutte-le-tracce","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2024\/06\/19\/maturita-2024-ecco-tutte-le-tracce\/","title":{"rendered":"Maturit\u00e0 2024. Ecco tutte le tracce"},"content":{"rendered":"\n<p>Oggi al via l&#8217;esame di Stato. Quest\u2019anno, l\u2019attesissimo quanto temuto esame vede una partecipazione di 526.317 candidati, di cui 512.530 interni e 13.787 esterni. Come riporta il sito specializzato orizzontescuola.it. Gli studenti saranno suddivisi in 28.038 classi e valutati da 14.072 commissioni d\u2019esame. La maggior parte dei candidati proviene dai licei, con 266.057 iscritti, seguiti dagli istituti tecnici (172.504) e dagli istituti professionali (87.756).<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n\n\n\n<p>Ecco le tracce.<div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n\n\n\n<p><a href=\"https:\/\/www.orizzontescuola.it\/maturita-2024-prima-prova-tutti-gli-aggiornamenti-in-tempo-reale-liveblog\/\">https:\/\/www.orizzontescuola.it\/maturita-2024-prima-prova-tutti-gli-aggiornamenti-in-tempo-reale-liveblog\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi al via l&#8217;esame di Stato. Quest\u2019anno, l\u2019attesissimo quanto temuto esame vede una partecipazione di 526.317 candidati, di cui 512.530 interni e 13.787 esterni. Come riporta il sito specializzato orizzontescuola.it. Gli studenti saranno suddivisi in 28.038 classi e valutati da 14.072 commissioni d\u2019esame. La maggior parte dei candidati proviene dai licei, con 266.057 iscritti, seguiti [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":201742,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[19],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2024\/06\/file1356897059_53-articlephoto-_thumb_720_480.jpg","author_info":{"display_name":"Redazione","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redazione\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/201741"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=201741"}],"version-history":[{"count":1,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/201741\/revisions"}],"predecessor-version":[{"id":201743,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/201741\/revisions\/201743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/201742"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=201741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=201741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=201741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}