{"id":198052,"date":"2024-05-16T20:08:01","date_gmt":"2024-05-16T18:08:01","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2024\/05\/16\/lavoro-meloni-siamo-su-strada-giusta-ma-non-ci-culliamo-su-allori\/"},"modified":"2024-05-16T20:08:01","modified_gmt":"2024-05-16T18:08:01","slug":"lavoro-meloni-siamo-su-strada-giusta-ma-non-ci-culliamo-su-allori","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2024\/05\/16\/lavoro-meloni-siamo-su-strada-giusta-ma-non-ci-culliamo-su-allori\/","title":{"rendered":"Lavoro, Meloni \u201cSiamo su strada giusta ma non ci culliamo su allori\u201d"},"content":{"rendered":"<div>FIRENZE (ITALPRESS) &#8211; &#8220;Il lavoro \u00e8 il cuore di questa manifestazione ed \u00e8 anche al centro del nostro impegno alla guida della Nazione. In questo anno e mezzo di governo abbiamo fatto le nostre scelte, abbiamo adottato i nostri provvedimenti avendo sempre ben in mente il ruolo che spetta esercitare allo Stato, cio\u00e8 mettere le aziende e i lavoratori nella condizione di creare occupazione e ricchezza, e redistribuire nel modo pi\u00f9 giusto possibile quella quota di ricchezza che con le tasse torna nelle mani dello Stato e che deve essere utilizzato per aiutare le persone pi\u00f9 fragili e pi\u00f9 esposte&#8221;. Lo ha detto il presidente del Consiglio, Giorgia Meloni, intervenendo con un videomessaggio al Festival del lavoro in cors di svolgimento a Firenze. <br \/>&#8220;Fin dal nostro insediamento abbiamo lavorato in questa direzione e i primi risultati ci dicono che siamo sulla strada giusta&#8221;, ha aggiunto. &#8220;Da quando siamo al governo abbiamo 600mila occupati in pi\u00f9 e il tasso occupazionale ha toccato il record del 62,1%, abbiamo superato per la prima volta il tetto dei dieci milioni di lavoratrici, i contratti stabili aumentano, la precariet\u00e0 diminuisce e si riducono anche gli inattivi, cio\u00e8 coloro che non solo non lavorano ma che anche hanno smesso di cercarlo un lavoro. E&#8217; un segnale molto positivo, di grande fiducia nell&#8217;economia ed anche nel futuro, dati che ci rendono orgogliosi e che anche il presidente della Repubblica Mattarella, che voglio ringraziare ancora una volta, ha salutato con soddisfazione. Non intendiamo ovviamente cullarci sugli allori, cio\u00e8 non significa che vada tutto bene. Noi continuiamo a lavorare per consolidare questi dati e migliorarli ancora&#8221;, ha concluso Meloni.<br \/>(ITALPRESS).<br \/>&#8211; Foto: Palazzo Chigi &#8211;<\/div>\n<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p><div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>FIRENZE (ITALPRESS) &#8211; &#8220;Il lavoro \u00e8 il cuore di questa manifestazione ed \u00e8 anche al centro del nostro impegno alla guida della Nazione. In questo anno e mezzo di governo abbiamo fatto le nostre scelte, abbiamo adottato i nostri provvedimenti avendo sempre ben in mente il ruolo che spetta esercitare allo Stato, cio\u00e8 mettere le [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":198053,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[446],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2024\/05\/20240516_1678.jpg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/198052"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=198052"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/198052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/198053"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=198052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=198052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=198052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}