{"id":183978,"date":"2024-01-18T09:04:47","date_gmt":"2024-01-18T08:04:47","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=183978"},"modified":"2024-01-18T09:05:18","modified_gmt":"2024-01-18T08:05:18","slug":"pizza-da-record-la-sfida-australiana-di-santoro","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2024\/01\/18\/pizza-da-record-la-sfida-australiana-di-santoro\/","title":{"rendered":"Pizza da record, la sfida australiana di Santoro"},"content":{"rendered":"\n<p>Giuseppe Santoro, noto promotore della pizza in tutto il comprensorio turistico sar\u00e1 domenica, in Australia protagonista di quella che pu\u00f3 essere considerata gi\u00e0 un&#8217;impresa. L&#8217;attuale presidente della Federazione italiana pizza preparer\u00e0 con la collaborazione di Pierre e Rosemary Moio, una pizza Nutella, Guiness world Record. La pizza sar\u00e1 lunga cento metri. Il tutto \u00e8 a scopo di beneficenza. Si vogliono, infatti, raccogliere fondi per la &#8220;Starlight Foundation&#8221; che si occupa di tanti giovani. &#8220;La pizza adesso &#8211; ha commentato Santoro &#8211; \u00e8 un brand italiano internazionale. Si sta cercando di spingere, ulteriormente, questo prodotto della nostra cucina pensando anche a dare aiuto a quanti si occupano di venire incontro alle esigenze di chi magari si trova in difficolt\u00e1&#8221;. Palcoscenico per eccellenza dell&#8217;evento sar\u00e1 il suburb di &#8220;Five Dock&#8221; area Italiana presso &#8220;The Home Grounds&#8221; di Sidney. Qui sar\u00e0 lanciata la sfida il cui ricavato andr\u00e0, appunto, tutto in beneficenza. Notevole gi\u00e1 il contributo donato sia da privati che imprese locali. Saranno piu di 4mila le slice &#8220;PizzaNutella&#8221; seguite dai programmi televisivi<br>&#8220;My Kitchen rule&#8221;, &#8220;Master Chef Australia&#8221; e &#8220;Master Chef India&#8221;. Tanti altri volti noti della Tv australiana aiuteranno in questa impresa Santoro, Pierre e Rosemary Moio. L&#8217;attivo presidente di Fip, sar\u00e1 presente, inoltre, in numerose trasmissioni. &#8220;The Daily Telegraph&#8221;, noto giornale australiano, ha gi\u00e1 parlato di questa singolare iniziativa che vedr\u00e1 anche la partecipazione degli chef Janelle Halil e Monzir Hamdin.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>Giuseppe Santoro, noto promotore della pizza in tutto il comprensorio turistico sar\u00e1 domenica, in Australia protagonista di quella che pu\u00f3 essere considerata gi\u00e0 un&#8217;impresa. L&#8217;attuale presidente della Federazione italiana pizza preparer\u00e0 con la collaborazione di Pierre e Rosemary Moio, una pizza Nutella, Guiness world Record. La pizza sar\u00e1 lunga cento metri. Il tutto \u00e8 a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":183981,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[3],"tags":[8965],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2024\/01\/IMG-20240118-WA0001-scaled.jpg","author_info":{"display_name":"redme","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redme\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/183978"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=183978"}],"version-history":[{"count":1,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/183978\/revisions"}],"predecessor-version":[{"id":183982,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/183978\/revisions\/183982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/183981"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=183978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=183978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=183978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}