{"id":174868,"date":"2023-10-31T08:30:01","date_gmt":"2023-10-31T07:30:01","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=174868"},"modified":"2023-10-31T08:30:03","modified_gmt":"2023-10-31T07:30:03","slug":"giardini-al-via-ledizione-zero-del-mediterranean-pizzapasta-show","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2023\/10\/31\/giardini-al-via-ledizione-zero-del-mediterranean-pizzapasta-show\/","title":{"rendered":"Giardini: al via l&#8217;edizione &#8220;Zero&#8221; del &#8220;Mediterranean pizza&#038;pasta Show&#8221;"},"content":{"rendered":"\n<p>Al via l&#8217;edizione &#8220;Zero&#8221; del &#8220;Mediterranean pizza &amp; pasta Show&#8221;. Il tutto si \u00e8 svolto nella splendida cornice di Pizza Store, villa Recanati della cittadina turistica, alla presenza di top chef, pizzaioli e pasticceri. E non poteva mancare un virtual che ha esportato le novit\u00e0 del settore oltre oceano. Tante le innovazioni di questo importante contest di due giornate che si sta svolgendo tra Taormina e Giardini Naxos. Presenti numerosi operatori del settore. Grazie al virtuale sono stati coinvolti esperti del settore di Francia, Ucraina, Bulgaria, Israele, Kuwait, Usa, e Australia. La giuria di questa gara del gusto \u00e8 stata composta da professionisti divisi in varie categorie e precisamente: &#8220;Identit\u00e0 pizza&#8221;, Carmela Guardione, segretaria &#8220;Slow Food Alcantara Taormina&#8221; e wedding planner di professione; Tony Rochetta un &#8220;contadino new generation&#8221; adesso grande professionista di Licata esperto nella valorizzazione dei grani antichi; Paolo Musarella, stimato capo barman &#8220;Aibes&#8221; che si \u00e8 contraddistinto negli anni in diversi locali della &#8220;Perla&#8221;; &#8220;Identit\u00e0 pasta&#8221;, chef Giovanni Cannav\u00f2, conosciutissimo nel comprensorio turistico per avere formato tanti bravi ed affermati colleghi; Giuseppe Messina, sommelier e manager di un noto ristorante di Taormina, da poco premiato come uno dei migliori siciliani; Giuseppe Calvaruso, chef stellato di un noto 2 stelle &#8220;Michelin&#8221; isolano; &#8220;Identit\u00e0 dessert&#8221;, Salvatore Ferrara, uno dei miglior barman degli anni d&#8217;oro che prosegue la sua professione in eventi e consulenze;<br>Salvatore Silvestro, maestro gelatiere, ma anche pasticciere con alle spalle tanti anni di professione; Michela Vitale, sommelier<br>studiosa del territorio non a caso manager in uno dei miglior due stelle &#8220;Michelin&#8221; siciliani. Numerosi i partner dell&#8217;evento tra cui: Carmelo Pagano di &#8220;Sicilia da Gustare&#8221;, Roberto Abbate di slow food Alcantara Taormina conosciuto come il &#8220;vignaiolo per passione&#8221;, fratelli Riggi, famiglia Chiti, Lillo Leonardo, Gianluca e Sabina Sozubir che hanno, appunto, accolto l&#8217;edizione di avvio della manifestazione. Grande impegno \u00e8 stato profuso anche da Corrado Bombaci segretario della &#8220;Federazione italiana pizzaioli&#8221; che ha coadiuvato il presidente Giuseppe Santoro, insieme a Sozubir in questa splendida iniziativa. Questi infine i vincitori nell&#8217;ordine del &#8220;Contest internazionale&#8221;: &#8220;Identit\u00e0 pasta&#8221;: Roberta Renci, Antonio Fucile e Lino Conti; &#8220;Identita Dessert&#8221;, Giuseppe Micalizzi, Vincenzo Fucile e Roberta Rinci; &#8220;Identit\u00e0 pizza&#8221;, Gaston Conti Ferraro, Massimo Sollenni e Natale Finocchio. Ognuno di loro si \u00e8 distinto perch\u00e9 ha proposto il meglio del territorio che non a caso era il tema del Contest. Award anche internazionali che sono andati in varie categorie a: Emanuele Ferraiuolo (Stati Uniti); Thierry Graffagnino (Francia), Abraham Bilotta (Inghilterra), Raanan Yossi Nussel (Israele), Giorgio Riggio (Kuwait), Francesco Crifo Roccella, Giuseppe Santoro, Tonys Skinny, Mark Paterno, Lorenzo Tron, Valerio Mollica (Australia), Radostin Kiryazov (Bulgaria) ed Emilio Giacometti (Scozia). &#8220;In attesa dell&#8217;edizione 2024 &#8211; ha commentato Santoro &#8211; va un grazie di cuore a tutti per questa grande opportunit\u00e0. A Taormina la giornata finale che vede addetti ai lavori, chef pizzaioli e pasticcieri in un simposio dai grandi temi in cui si \u00e8 discusso di territorio, sostenibilit\u00e0 e quanto ancora vede protagonista il nostro Mediterraneo&#8221;.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>Al via l&#8217;edizione &#8220;Zero&#8221; del &#8220;Mediterranean pizza &amp; pasta Show&#8221;. Il tutto si \u00e8 svolto nella splendida cornice di Pizza Store, villa Recanati della cittadina turistica, alla presenza di top chef, pizzaioli e pasticceri. E non poteva mancare un virtual che ha esportato le novit\u00e0 del settore oltre oceano. Tante le innovazioni di questo importante [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":174869,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[13,15],"tags":[8965],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2023\/10\/IMG-20231031-WA0001.jpg","author_info":{"display_name":"redme","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redme\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/174868"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=174868"}],"version-history":[{"count":1,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/174868\/revisions"}],"predecessor-version":[{"id":174870,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/174868\/revisions\/174870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/174869"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=174868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=174868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=174868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}