{"id":17036,"date":"2018-03-17T17:33:09","date_gmt":"2018-03-17T16:33:09","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=17036"},"modified":"2018-03-17T17:33:09","modified_gmt":"2018-03-17T16:33:09","slug":"leggendario-nibali-trionfo-alla-milano-sanremo","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2018\/03\/17\/leggendario-nibali-trionfo-alla-milano-sanremo\/","title":{"rendered":"Leggendario Nibali: trionfo alla Milano-Sanremo"},"content":{"rendered":"<div class=\"paragrafo clearfix\">\nVincenzo Nibali \u00e8 nella storia. Con una incredibile azione sul Poggio il camiche messinese della Bahrein-Merida \u00e8 andato in fuga e ha trionfato in solitaria nella 109\u00aa edizione della Milano-Sanremo.<br \/>\nUn&#8217;impresa studiata e meravigliosa, con i grandi favoriti, dal campione del mondo Sagan al vincitore dell&#8217;anno scorso Kwiatkowski che si sono curati tra di loro senza organizzarsi nell&#8217;andare a riprendere lo &#8220;Squalo dello Stretto&#8221;.<br \/>\n\u00c8 il primo successo di Nibali alla Classicissima, che corona una carriera ed un palmares da sogno.<br \/>\nA cinquanta metri dal traguardo mi sono preso un sospiro per gustarmi la vittoria, un&#8217;emozione unica &#8211; ha affermato Vincenzo Nibali -. Non pensavo di potercela fare, a volte la fortuna ti sorride.<br \/>\nSono partito perch\u00e9 ho visto che c&#8217;era un vuoto. Ho fatto il mio ritmo fino alla fine senza mai girarmi.<br \/>\nLa parte pi\u00f9 difficile sono stati gli ultimi due chilometri, avevo il vento in faccia e avevo solo voglia di arrivare al traguardo, non vedevo l&#8217;ora e non finivano pi\u00f9 quei due viali. Non sapevo dove era il gruppo ed avevo paura a voltarmi&#8221;.\n<\/div>\n<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p><div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>Vincenzo Nibali \u00e8 nella storia. Con una incredibile azione sul Poggio il camiche messinese della Bahrein-Merida \u00e8 andato in fuga e ha trionfato in solitaria nella 109\u00aa edizione della Milano-Sanremo. Un&#8217;impresa studiata e meravigliosa, con i grandi favoriti, dal campione del mondo Sagan al vincitore dell&#8217;anno scorso Kwiatkowski che si sono curati tra di loro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":253,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[8,9],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2017\/05\/Nibali-Vincenzo-2.jpg","author_info":{"display_name":"Redazione","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redazione\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/17036"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=17036"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/17036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/253"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=17036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=17036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=17036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}