{"id":159161,"date":"2023-06-14T12:07:58","date_gmt":"2023-06-14T10:07:58","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2023\/06\/14\/bagnaia-arrivo-in-germania-con-la-giusta-carica\/"},"modified":"2023-06-14T12:07:58","modified_gmt":"2023-06-14T10:07:58","slug":"bagnaia-arrivo-in-germania-con-la-giusta-carica","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2023\/06\/14\/bagnaia-arrivo-in-germania-con-la-giusta-carica\/","title":{"rendered":"Bagnaia \u201cArrivo in Germania con la giusta carica\u201d"},"content":{"rendered":"<div>ROMA (ITALPRESS) &#8211; Archiviato un fine settimana perfetto al Mugello con la vittoria di Pecco Bagnaia, autore anche della pole position, del giro veloce in gara e vincitore della gara Sprint del sabato, il Ducati Lenovo Team \u00e8 pronto a scendere nuovamente in pista per il GP della Germania. Ad ospitare il settimo appuntamento della stagione MotoGP 2023 sar\u00e0 il circuito del Sachsenring, situato nel nord del paese a pochi chilometri dalla cittadina di Chemnitz. Bagnaia, che lo scorso anno aveva raggiunto il suo deficit maggiore in campionato provo al Sachsenring a seguito di una caduta (-91 punti), arriva quest&#8217;anno all&#8217;appuntamento tedesco da leader del mondiale con 21 lunghezze di vantaggio sul secondo classificato, il compagno di marca Marco Bezzecchi (VR46 Racing Team). &#8220;Il fine settimana al Mugello \u00e8 stato davvero perfetto e mi ha dato la giusta carica per affrontare anche il GP di Germania &#8211; assicura il pilota piemontese, iridato in carica &#8211; Sicuramente conoscevo molto bene il tracciato toscano e questo mi ha aiutato, ma \u00e8 il feeling con la mia Desmosedici che mi ha permesso di fare veramente la differenza. Spero di ritrovare subito queste sensazioni anche al Sachsenring: l&#8217;obiettivo sar\u00e0 sempre lo stesso. Lavorare bene fin dalle prime sessioni per arrivare pronto sia per la Sprint che per la gara di domenica&#8221;. Occupa invece la ventesima posizione in Campionato Enea Bastianini, che ha corso il suo primo GP quest&#8217;anno domenica scorsa al Mugello. Il pilota romagnolo,  ancora non al 100% della sua forma fisica, \u00e8 riuscito a chiudere sia la Sprint che la gara domenicale in top ten, un risultato al di sopra delle aspettative considerata la lunga assenza dalle corse dopo l&#8217;infortunio di Portim\u00e0o a met\u00e0 marzo. Sul tracciato del Sachsenring, fisicamente meno impegnativo rispetto al Mugello, Bastianini punter\u00e0 ad essere pi\u00f9 competitivo. &#8220;Sono contento di poter tornare subito in pista &#8211; ammette il ducatista &#8211; Il weekend al Mugello si \u00e8 rivelato positivo e, anche se ho faticato molto in gara, sono riuscito ad ottenere un risultato che all&#8217;inizio non mi sarei mai aspettato. Ci vorr\u00e0 ancora del tempo per essere al 100%, ma sicuramente il Sachsenring sar\u00e0 meno impegnativo fisicamente rispetto al circuito toscano, e perci\u00f2 spero di poter fare ancora meglio nel GP della Germania&#8221;.<br \/>&#8211; Foto Image &#8211;<br \/>(ITALPRESS).<\/div>\n<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p><div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; Archiviato un fine settimana perfetto al Mugello con la vittoria di Pecco Bagnaia, autore anche della pole position, del giro veloce in gara e vincitore della gara Sprint del sabato, il Ducati Lenovo Team \u00e8 pronto a scendere nuovamente in pista per il GP della Germania. Ad ospitare il settimo appuntamento della [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":159162,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[446],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2023\/06\/20230614_0224.jpg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/159161"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=159161"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/159161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/159162"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=159161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=159161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=159161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}