{"id":127404,"date":"2022-10-26T17:52:38","date_gmt":"2022-10-26T15:52:38","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=127404"},"modified":"2022-10-26T17:52:40","modified_gmt":"2022-10-26T15:52:40","slug":"elezioni-universitarie-orum-piglia-tutto-anche-il-nucleo-di-valutazione","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2022\/10\/26\/elezioni-universitarie-orum-piglia-tutto-anche-il-nucleo-di-valutazione\/","title":{"rendered":"Elezioni universitarie, Orum piglia tutto, anche il nucleo di valutazione"},"content":{"rendered":"\n<p>In data 25 Ottobre 2022 si sono svolte le votazioni per l\u2019Elezione del rappresentante degli studenti in seno al Nucleo di Valutazione di Ateneo.<br>Il Nucleo di valutazione ha il compito di verificare la corretta gestione delle risorse pubbliche, la produttivit\u00e0 della ricerca e della didattica, nonch\u00e8 l&#8217;imparzialit\u00e0 ed il buon andamento dell&#8217;azione amministrativa.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n\n\n\n<p>Questo organo di rappresentanza viene votato dai rappresentanti degli studenti in seno agli Organi Superiori dell\u2019Ateneo e dai rappresentanti della Consulta di tutti i Dipartimenti.<div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"http:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2022\/10\/Orum-1.jpg\" alt=\"\" class=\"wp-image-127406\" srcset=\"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2022\/10\/Orum-1.jpg 1024w, https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2022\/10\/Orum-1-300x225.jpg 300w, https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2022\/10\/Orum-1-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Nelle votazioni di oggi la compagine Orum, che grazie alla schiacciante vittoria delle precedenti elezioni in cui ha conquistato 8 organi su 9 e la quasi totalit\u00e0 delle consulte, ha espresso la candidatura votata all\u2019unanimit\u00e0 di Gioacchino Sacheli.<\/p>\n\n\n\n<p>Gioacchino, studente del 5\u00b0 anno di Medicina e Chirurgia, gi\u00e0 per il secondo mandato rappresentante degli studenti in seno al Corso di Laurea e al Dipartimento di Patologia Umana, membro dell&#8217;associazione Morgana e di Azione Universitaria, \u00e8 stato eletto al Nucleo di Valutazione con 19 voti su 19.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In data 25 Ottobre 2022 si sono svolte le votazioni per l\u2019Elezione del rappresentante degli studenti in seno al Nucleo di Valutazione di Ateneo.Il Nucleo di valutazione ha il compito di verificare la corretta gestione delle risorse pubbliche, la produttivit\u00e0 della ricerca e della didattica, nonch\u00e8 l&#8217;imparzialit\u00e0 ed il buon andamento dell&#8217;azione amministrativa. Questo organo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":127405,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[4],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2022\/10\/Orum-2.jpg","author_info":{"display_name":"red..me","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redstage\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/127404"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=127404"}],"version-history":[{"count":1,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/127404\/revisions"}],"predecessor-version":[{"id":127407,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/127404\/revisions\/127407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/127405"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=127404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=127404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=127404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}