{"id":125948,"date":"2022-10-16T11:27:29","date_gmt":"2022-10-16T09:27:29","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=125948"},"modified":"2022-10-16T11:30:25","modified_gmt":"2022-10-16T09:30:25","slug":"contrasto-caporalato-se-ne-parla-a-palazzo-zanca","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2022\/10\/16\/contrasto-caporalato-se-ne-parla-a-palazzo-zanca\/","title":{"rendered":"Contrasto caporalato, se ne parla a Palazzo Zanca"},"content":{"rendered":"\n<p>Domani, luned\u00ec 17, alle ore 15.30, al Palacultura \u201cAntonello da Messina\u201d, si terr\u00e0 l\u2019incontro promosso dall\u2019Ufficio Immigrazione e co-organizzato dal Comune di Messina sul contrasto al caporalato in agricoltura. Al convegno prenderanno parte il Sindaco <strong>Federico Basile, <\/strong>il vice Prefetto vicario <strong>Patrizia Adorno,<\/strong> l\u2019Assessore alle Politiche Sociali Alessandra Calafiore, il Vescovo ausiliario Mons. <strong>Cesare Di Pietro<\/strong> e un funzionario della Questura di Messina.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n\n\n\n<p> I lavori saranno avviati dalla dirigente dell\u2019Ufficio Speciale Immigrazione <strong>Michela Bongiorno, <\/strong>con la presentazione della campagna regionale di informazione e sensibilizzazione contro lo sfruttamento dei lavoratori stranieri in agricoltura denominata \u201cDiritti negli occhi\u201d, il cui intento \u00e8 il coinvolgimento della societ\u00e0 civile nel processo di emersione e contrasto al caporalato nel territorio siciliano. Gli interventi previsti riguardano le azioni gi\u00e0 svolte dall\u2019Ufficio Speciale Immigrazione sul territorio regionale, nell\u2019ambito di\u00a0Su.Pr.Eme. <div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n\n\n\n<p>Italia tramite il Polo Sociale Integrato di Messina, relativi al progetto realizzato da Medihospes Cooperativa Sociale e dal Comune di Messina, finalizzato a favorire l\u2019inserimento sociale, lavorativo e culturale dei cittadini stranieri attraverso una \u00e9quipe multi disciplinare che eroga servizi presso un Polo fisso ed un Polo mobile operante su tutto il territorio provinciale. L\u2019incontro, sar\u00e0 occasione inoltre per discutere in merito all\u2019attuazione della legge regionale per l\u2019accoglienza e l\u2019inclusione e del progetto Prisma, cui seguir\u00e0 un approfondimento sui temi dell\u2019inclusione, della tratta e dell\u2019istruzione. Gli interventi, moderati dal giornalista <strong>Emilio Pintaldi, <\/strong>prevedono un confronto tra i sindacati Flai CGIL, Anolf-CISL, enti del terzo settore (Migrantes), associazioni datoriali e la Comunit\u00e0 Islamica per discutere del rispetto del lavoro e dei diritti dei migranti impegnati nei campi e del contrasto al caporalato. Parteciperanno tra il pubblico anche gli amministratori locali che hanno aderito al progetto del Polo Sociale Integrato e gli studenti degli Istituti superiori e del CPIA di Messina. <\/p>\n\n\n\n<p>L\u2019obiettivo della campagna di sensibilizzazione \u00e8 offrire un approccio partecipativo per favorire i processi di sensibilizzazione alle tematiche delicate a cui\u00a0Su.Pr.Eme. Italia rivolge l\u2019attenzione: il rispetto del lavoro e dei diritti dei migranti impegnati nei campi e il contrasto ad ogni forma di illegalit\u00e0. Il progetto\u00a0Su.Pr.Eme. \u00e8 finanziato dai fondi AMIF- Emergency Funds della Commissione Europea \u2013 DG Migration and Home Affairs. <\/p>\n\n\n\n<p>Il partenariato \u00e8 guidato dal Ministero del Lavoro e delle Politiche Sociali \u2013 Direzione Generale Immigrazione (Lead partner) coadiuvato dalla Regione Puglia (Coordinating Partner) insieme alle Regioni Basilicata, Calabria, Campania e Sicilia e l\u2019Ispettorato Nazionale del Lavoro, l\u2019Organizzazione Internazionale per le Migrazioni e Nova consorzio nazionale. A conclusione del programma della giornata \u00e8 previsto un momento di spettacolo narrativo \u201cI Cunti del Caporalato\u201d a cura del cantastorie <strong>Salvo Piparo <\/strong>accompagnato musicalmente da <strong>Michele Piccione,<\/strong> ispirato alle storie realmente vissute da ragazzi migranti sopravvissuti al viaggio migratorio, che oggi risiedono e lavorano legalmente nelle regioni del Sud Italia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani, luned\u00ec 17, alle ore 15.30, al Palacultura \u201cAntonello da Messina\u201d, si terr\u00e0 l\u2019incontro promosso dall\u2019Ufficio Immigrazione e co-organizzato dal Comune di Messina sul contrasto al caporalato in agricoltura. Al convegno prenderanno parte il Sindaco Federico Basile, il vice Prefetto vicario Patrizia Adorno, l\u2019Assessore alle Politiche Sociali Alessandra Calafiore, il Vescovo ausiliario Mons. Cesare Di [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":125949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[4],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2022\/10\/Palazzo-Zanca.jpg","author_info":{"display_name":"red..me","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redstage\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/125948"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=125948"}],"version-history":[{"count":3,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/125948\/revisions"}],"predecessor-version":[{"id":125952,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/125948\/revisions\/125952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/125949"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=125948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=125948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=125948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}