{"id":120697,"date":"2022-09-07T17:02:29","date_gmt":"2022-09-07T15:02:29","guid":{"rendered":"http:\/\/www.messinaoggi.it\/website\/?p=120697"},"modified":"2022-09-07T17:02:32","modified_gmt":"2022-09-07T15:02:32","slug":"antonio-de-luca-m5s-mi-ricandido-per-continuare-le-battaglie-iniziate","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2022\/09\/07\/antonio-de-luca-m5s-mi-ricandido-per-continuare-le-battaglie-iniziate\/","title":{"rendered":"Antonio De Luca (M5S): &#8220;mi ricandido per continuare le battaglie iniziate&#8221;"},"content":{"rendered":"\n<p>&#8220;Ho deciso di ricandidarmi perch\u00e9 sono troppe le cose ancora da fare in Sicilia e voglio portare avanti le battaglie iniziate durante il mandato appena concluso&#8221;. <div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n\n\n\n<p>Cos\u00ec il deputato regionale uscente <strong>Antonio De Luca,<\/strong> che in conferenza stampa ha spiegato le ragioni che lo hanno indotto a scendere nuovamente in campo con il Movimento Cinque Stelle per le regionali del prossimo 25 settembre.<div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p>\n\n\n\n<p>&#8220;In questi cinque anni all&#8217;Ars &#8211; ha affermato il parlamentare pentastellato &#8211;<br>mi sono battuto affinch\u00e9 la Sicilia avesse autostrade sicure, una sanit\u00e0 efficiente e vedesse la fine delle sacche di precariato che coinvolgono decine di lavoratori. Sono stato al fianco dei lavoratori ex Ferrotel e Servirail; mi sono battuto per il personale del 118,servizio di fondamentale importanza via via smantellato da una politica cieca e poco attenta alle esigenze primarie dei cittadini. Mi sono fatto portavoce del grido di allarme della popolazione eoliana, il cui diritto alla salute \u00e8 stato sovente calpestato : l&#8217;ospedale di Lipari non \u00e8 sufficientemente attrezzato, n\u00e9 in termini di personale n\u00e9 in termini di strumentazioni, per soddisfare le richieste di prestazioni sanitarie adeguate. Ho denunciato l&#8217;inefficacia della politica sanitaria del Governo Musumeci , che \u00e8 stata fallimentare sotto ogni punto di vista. Basti pensare alle liste d&#8217;attesa lunghissime, alla totale inerzia sul punto nascita di Sant&#8217;Agata Militello, all&#8217; assenza di soluzioni ai problemi dei residenti delle zone disagiate, che hanno il diritto di avere ospedali vicini e pienamente operativi &#8220;.<\/p>\n\n\n\n<p>&#8221; Con passione e dedizione- ha continuato l&#8217;on. Antonio De Luca &#8211; mi sono impegnato affinch\u00e9 venissero trovate soluzioni concrete a problemi atavici di questa nostra terra, pensando sempre all&#8217;interesse dei cittadini e mai al mio tornaconto personale&#8221;.<\/p>\n\n\n\n<p>&#8220;In questi anni non mi sono mai risparmiato e voglio continuare a dare il mio contributo per far rinascere la Sicilia, terra in cui sono nato e nella quale ho deciso di restare a vivere&#8221;.<\/p>\n\n\n\n<p>&#8220;Alle prossime elezioni &#8211; ha concluso il deputato regionale &#8211; sar\u00f2 ancora candidato con il Movimento Cinque Stelle, che considero una seconda casa, costruita con i valori nei quali ho sempre creduto. Se verr\u00f2 rieletto, avr\u00f2 un&#8217;unica missione: stare sempre dalla parte dei cittadini&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Ho deciso di ricandidarmi perch\u00e9 sono troppe le cose ancora da fare in Sicilia e voglio portare avanti le battaglie iniziate durante il mandato appena concluso&#8221;. Cos\u00ec il deputato regionale uscente Antonio De Luca, che in conferenza stampa ha spiegato le ragioni che lo hanno indotto a scendere nuovamente in campo con il Movimento Cinque [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":120698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[4],"tags":[],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2022\/09\/Antonio-De-Luca-regionali.jpg","author_info":{"display_name":"red..me","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/redstage\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/120697"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=120697"}],"version-history":[{"count":1,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/120697\/revisions"}],"predecessor-version":[{"id":120699,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/120697\/revisions\/120699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/120698"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=120697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=120697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=120697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}