{"id":107151,"date":"2022-05-09T10:07:36","date_gmt":"2022-05-09T08:07:36","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2022\/05\/09\/cozzoli-abbiamo-portato-lo-sport-ovunque\/"},"modified":"2022-05-09T10:07:36","modified_gmt":"2022-05-09T08:07:36","slug":"cozzoli-abbiamo-portato-lo-sport-ovunque","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2022\/05\/09\/cozzoli-abbiamo-portato-lo-sport-ovunque\/","title":{"rendered":"Cozzoli \u201cAbbiamo portato lo sport ovunque\u201d"},"content":{"rendered":"<div>ROMA (ITALPRESS) &#8211; &#8220;Siamo la societ\u00e0 dello Stato che promuove e investe nello sport e nell&#8217;attivit\u00e0 fisica, con obiettivi anche in termini di impatto socioeconomico. Operiamo attraverso un piano sociale e industriale approvato dal governo e fondato su interventi inclusivi, sostenibili e accessibili sui territori. Abbiamo portato lo sport ovunque&#8221;. A parlare, sul supplemento economico del &#8216;Corriere della Ser\u00e0, \u00e8 il presidente di Sport e Salute, Vito Cozzoli. &#8220;Abbiamo fin da subito improntato l&#8217;operativit\u00e0 alla leale collaborazione con il Coni e direi che oggi l&#8217;ambito \u00e8 definito &#8211; sottolinea Cozzoli &#8211; Noi ci occupiamo dello sport di base e della crescita della pratica sportiva da parte degli italiani, mentre il Coni si dedica allo sport di alto livello e alle Olimpiadi. I risultati raggiunti in occasione degli ultimi Giochi olimpici sono la riprova che la riforma ha funzionato. Si \u00e8 chiuso il cerchio in modo virtuoso, con un presidio che va dal praticante al campione&#8221;. E ancora: &#8220;La resistenza l&#8217;ho capita, ma non la giustifico. La necessit\u00e0 di un cambiamento era sotto gli occhi di tutti e lo Stato ha inteso ridare centralit\u00e0 al tema delle politiche pubbliche in materia di sport con una riforma che sta producendo i risultati attesi&#8221;. Sport e Salute \u00e8 stato al fianco di organismi e federazioni: &#8220;In tutto oltre 2,3 miliardi per sostenere e finanziare lo sport italiano, nel corso di quest&#8217;anno abbiamo gi\u00e0 erogato 288 milioni di euro. Il pi\u00f9 grande investimento \u00e8 stata la scuola: oggi 1,7 milioni di bambini fa sport grazie a Sport e Salute&#8221;. Lo scorso anno \u00e8 stata presentata la app Mysportesalute, una app in grado di collegare le societ\u00e0 sportive, quasi 8 mila comuni italiani con una mappatura di 77 mila impianti sportivi: &#8220;Una delle premesse da cui siamo partiti \u00e8 il dato che vede l&#8217;Italia al quinto posto in Europa nella classifica dei paesi pi\u00f9 sedentari. La situazione ereditata da Sport e Salute alla sua nascita era la seguente: 25 milioni di persone in sovrappeso e 22 milioni di sedentari, cifre che si traducono in inevitabili costi sul bilancio della sanit\u00e0 pubblica. L&#8217;obiettivo dovrebbe, invece, essere quello di ridurre parte di questi costi e reinvestire le risorse risparmiate nello sport e nella prevenzione. Vogliamo far crescere lo sport anche grazie all&#8217;innovazione &#8211; conclude Cozzoli &#8211; Al momento sono 230 le startup che si sono candidate al programma di accelerazione WeSportUP dell&#8217;hub del Foro Italico&#8221;.<br \/>&#8211; foto agenziafotogramma.it &#8211;<br \/>(ITALPRESS).<\/div>\n<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p><div id=\"videoincontent\" style=\"clear:both\";><\/div>","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; &#8220;Siamo la societ\u00e0 dello Stato che promuove e investe nello sport e nell&#8217;attivit\u00e0 fisica, con obiettivi anche in termini di impatto socioeconomico. Operiamo attraverso un piano sociale e industriale approvato dal governo e fondato su interventi inclusivi, sostenibili e accessibili sui territori. Abbiamo portato lo sport ovunque&#8221;. A parlare, sul supplemento economico [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":107152,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[446],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2022\/05\/20220509_0268.jpg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/107151"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=107151"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/107151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/107152"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=107151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=107151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=107151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}