{"id":107112,"date":"2022-05-08T18:07:35","date_gmt":"2022-05-08T16:07:35","guid":{"rendered":"https:\/\/www.messinaoggi.it\/website\/2022\/05\/08\/ucraina-von-der-leyen-il-male-e-tornato-dopo-72-anni-ma-vinceremo-la-sfida\/"},"modified":"2022-05-08T18:07:35","modified_gmt":"2022-05-08T16:07:35","slug":"ucraina-von-der-leyen-il-male-e-tornato-dopo-72-anni-ma-vinceremo-la-sfida","status":"publish","type":"post","link":"https:\/\/www.messinaoggi.it\/website\/2022\/05\/08\/ucraina-von-der-leyen-il-male-e-tornato-dopo-72-anni-ma-vinceremo-la-sfida\/","title":{"rendered":"Ucraina, Von Der Leyen \u201cIl male \u00e8 tornato dopo 72 anni ma vinceremo la sfida\u201d"},"content":{"rendered":"<div>ROMA (ITALPRESS) &#8211; &#8220;Oggi il nostro continente incontra le ombre di un passato che pensavamo di aver lasciato da tempo. Una guerra atroce, un&#8217;aggressione insensata e citt\u00e0 distrutte. Ci sono milioni di innocenti che fuggono e un popolo che lotta disperatamente per determinare il proprio futuro. L&#8217;Europa \u00e8 al fianco dell&#8217;Ucraina. L&#8217;invasione della Russia ci ricorda perch\u00e8 oggi celebriamo la giornata dell&#8217;Europa. Il giorno in cui nacque la nostra Europa pacifica, prospera e unita. Settantadue anni dopo \u00e8 tornato il male, ma l&#8217;Europa \u00e8 pi\u00f9 forte e unita che mai&#8221;. Lo ha detto Ursula von der Leyen, presidente della Commissione europea, in occasione della Giornata dell&#8217;Europa. E ha aggiunto: &#8220;Ci stiamo riprendendo dall&#8217;emergenza Covid. Gli Stati membri hanno ricevuto 100 miliardi di euro dal fondo Next Generation Eu. Stiamo lavorando duramente per proteggere il clima e rendere il nostro Continente indipendente dalle energie fossili importate. La nostra Unione sta creando regole per la nuova era digitale oltre i nostri confini. L&#8217;Europa ha potuto realizzare tutte queste cose perch\u00e8 unita e determinata. Per questo sono convinta e ottimista che la nostra Unione possa vincere la sfida posta dalla guerra in Ucraina&#8221;.<div id=\"div-gpt-ad-Messinaoggi.it-DSK-300x250-corpoart\" style=\"text-align:center;margin:0 auto;\"><\/div><\/p>\n<p>Photo credit: agenziafotogramma.it<br \/>\n(ITALPRESS).<div id=\"videoincontent\" style=\"clear:both\";><\/div><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; &#8220;Oggi il nostro continente incontra le ombre di un passato che pensavamo di aver lasciato da tempo. Una guerra atroce, un&#8217;aggressione insensata e citt\u00e0 distrutte. Ci sono milioni di innocenti che fuggono e un popolo che lotta disperatamente per determinare il proprio futuro. L&#8217;Europa \u00e8 al fianco dell&#8217;Ucraina. L&#8217;invasione della Russia ci [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":107113,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":"","_mi_skip_tracking":false},"categories":[446],"tags":[783],"featured_image_src":"https:\/\/www.messinaoggi.it\/website\/wp-content\/uploads\/2022\/05\/20220508_1899.jpg","author_info":{"display_name":"Admin","author_link":"https:\/\/www.messinaoggi.it\/website\/author\/admin\/"},"digistream_id":0,"digistream":false,"_links":{"self":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/107112"}],"collection":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/comments?post=107112"}],"version-history":[{"count":0,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/posts\/107112\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media\/107113"}],"wp:attachment":[{"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/media?parent=107112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/categories?post=107112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.messinaoggi.it\/website\/wp-json\/wp\/v2\/tags?post=107112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}